{"id":66702,"date":"2024-04-17T09:55:50","date_gmt":"2024-04-17T07:55:50","guid":{"rendered":"https:\/\/ga-p.com\/sector\/farma-y-salud\/"},"modified":"2025-06-04T17:31:35","modified_gmt":"2025-06-04T15:31:35","slug":"farmaceutico-e-saude","status":"publish","type":"sector","link":"https:\/\/ga-p.com\/pt-pt\/sector\/farmaceutico-e-saude\/","title":{"rendered":"Farmac\u00eautico e Sa\u00fade"},"content":{"rendered":"\n<div id=\"AreasSectoresHeader-block_53d4d52780eb1d3e2293ee968a603256\" class=\"AreasSectoresHeader\">\n\n    <div class=\"container\">\n        <div class=\"row\">\n            <div class=\"col-12 col-lg-10\">\n                                    <div class=\"pretitulo\"><p class=''>Sector<\/p>\n<\/div>\n                                <div class=\"titulo\">\n                    <p class=''>Farmac\u00eautico e Sa\u00fade<\/p>\n                <\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n\n    <style>\n        .AreasSectoresHeader{opacity:0;height:100vw;}\n        .AreasSectoresHeader .titulo * { background-image: url(https:\/\/ga-p.com\/wp-content\/uploads\/2024\/04\/Farma-y-Ciencias-de-la-Salud-scaled.jpg); }\n    <\/style>\n\n<\/div>\n\n\n\n\n\n\n<div id=\"Cita-block_3f30e3f29eadbec4166d54357eefcd2f\" class=\"Cita customContainer right\">\n    <div class=\"quoteBlock\">\n        <div class=\"quoteContent\">\n            <div class=\"texto\"><h2>&#8220;They have large, highly qualified multidisciplinary team that is very prepared and very coordinated.&#8221;<\/h2>\n<\/div>\n                        <div class=\"mencion\">Chambers &#038; Partners Europe<\/div>\n                    <\/div>\n    <\/div>\n<\/div>\n\n<div id=\"ColumnaMasSidebar-block_c1115a61ea4c894f1d206319776f901b\" class=\"ColumnaMasSidebar v2\">\n    <div class=\"container\">\n                <div class=\"hero-inner-blocks\">\n<div id=\"ColumnaIzquierda-block_b90c9d4601def9717598e7f10e84d575\" class=\"blanco ColumnaIzquierda\">\n    <div class=\"acf-innerblocks-container\">\n\n\n<div id=\"TituloTexto-block_ab779360e120624ac61625d236c2b89e\" class=\"TituloTexto v2\">\n    <div class=\"customContainer right\">\n        <div class=\"textContainer \">\n            <div>\n                                <div class=\"texto\"><p>A nossa equipa de Farmac\u00eautico e Sa\u00fade re\u00fane especialistas de v\u00e1rias \u00e1reas de pr\u00e1tica para prestar um aconselhamento jur\u00eddico abrangente \u00e0s empresas deste sector. Num contexto econ\u00f3mico em que a inova\u00e7\u00e3o e a regula\u00e7\u00e3o s\u00e3o cruciais, a nossa equipa participa ativamente no aconselhamento de um sector em constante evolu\u00e7\u00e3o, oferecendo uma abordagem global e hol\u00edstica.<\/p>\n<p>Em Espanha, o sector da sa\u00fade e farmac\u00eautico, com um crescimento cont\u00ednuo impulsionado pela procura de solu\u00e7\u00f5es inovadoras na \u00e1rea da sa\u00fade e da biotecnologia, desempenha um papel fundamental na economia. Neste cen\u00e1rio din\u00e2mico, a nossa equipa abrange um espetro completo de conhecimentos e compet\u00eancias, desde a prote\u00e7\u00e3o da propriedade intelectual ao desenvolvimento de neg\u00f3cios e quest\u00f5es de concorr\u00eancia, promo\u00e7\u00e3o e distribui\u00e7\u00e3o, incluindo uma vasta experi\u00eancia em contratos com as administra\u00e7\u00f5es de sa\u00fade.<\/p>\n<\/div>\n            <\/div>\n                    <\/div>\n    <\/div>\n<\/div>\n\n\n<div id=\"AcordeonMultiple-block_75ed5268364843202d17142bbe722d47\" class=\" AcordeonMultiple\">\n\n    <div class=\"imagen\" style=\"background:url(https:\/\/ga-p.com\/wp-content\/uploads\/2024\/04\/Farma-y-Ciencias-de-la-Salud-scaled.jpg)\"><\/div>\n    <div class=\"contenido\">\n        <div class=\"title pe-3\"><p class=''>As nossas \u00e1reas de especializa\u00e7\u00e3o s\u00e3o as seguintes:<\/p>\n<\/div>\n        <div class=\"accordion accordion-flush\" id=\"accordion-block_75ed5268364843202d17142bbe722d47\">\n                        <div class=\"accordion-item\">\n                    <h2 class=\"accordion-header\">\n                        <button class=\"accordion-button collapsed gap-3 align-items-start has-text\" type=\"button\" data-bs-toggle=\"collapse\" data-bs-target=\"#flush-0\"  aria-expanded=\"false\" aria-controls=\"flush-0\">\n                            Propriedade intelectual                        <\/button>\n                    <\/h2>\n                    <div id=\"flush-0\" class=\"accordion-collapse collapse\" data-bs-parent=\"#accordion-block_75ed5268364843202d17142bbe722d47\">\n                        <div class=\"accordion-body\">\n                            <p>Desenvolvimento de produtos, licenciamento, patentes, marcas comerciais e prote\u00e7\u00e3o de dados.<\/p>\n                        <\/div>\n                    <\/div>\n                <\/div>\n                        <div class=\"accordion-item\">\n                    <h2 class=\"accordion-header\">\n                        <button class=\"accordion-button collapsed gap-3 align-items-start has-text\" type=\"button\" data-bs-toggle=\"collapse\" data-bs-target=\"#flush-1\"  aria-expanded=\"false\" aria-controls=\"flush-1\">\n                            Neg\u00f3cios e finan\u00e7as                        <\/button>\n                    <\/h2>\n                    <div id=\"flush-1\" class=\"accordion-collapse collapse\" data-bs-parent=\"#accordion-block_75ed5268364843202d17142bbe722d47\">\n                        <div class=\"accordion-body\">\n                            <p>Finan\u00e7as empresariais, fus\u00f5es e aquisi\u00e7\u00f5es, corporate governance e estrat\u00e9gias de investimento<\/p>\n                        <\/div>\n                    <\/div>\n                <\/div>\n                        <div class=\"accordion-item\">\n                    <h2 class=\"accordion-header\">\n                        <button class=\"accordion-button collapsed gap-3 align-items-start has-text\" type=\"button\" data-bs-toggle=\"collapse\" data-bs-target=\"#flush-2\"  aria-expanded=\"false\" aria-controls=\"flush-2\">\n                            Concorr\u00eancia                        <\/button>\n                    <\/h2>\n                    <div id=\"flush-2\" class=\"accordion-collapse collapse\" data-bs-parent=\"#accordion-block_75ed5268364843202d17142bbe722d47\">\n                        <div class=\"accordion-body\">\n                            <p>Regulamenta\u00e7\u00e3o comercial, contratos p\u00fablicos, com\u00e9rcio internacional e concorr\u00eancia desleal.<\/p>\n                        <\/div>\n                    <\/div>\n                <\/div>\n                        <div class=\"accordion-item\">\n                    <h2 class=\"accordion-header\">\n                        <button class=\"accordion-button collapsed gap-3 align-items-start has-text\" type=\"button\" data-bs-toggle=\"collapse\" data-bs-target=\"#flush-3\"  aria-expanded=\"false\" aria-controls=\"flush-3\">\n                            Contencioso                        <\/button>\n                    <\/h2>\n                    <div id=\"flush-3\" class=\"accordion-collapse collapse\" data-bs-parent=\"#accordion-block_75ed5268364843202d17142bbe722d47\">\n                        <div class=\"accordion-body\">\n                            <p>Responsabilidade por produtos defeituosos, lit\u00edgios comerciais e lit\u00edgios em mat\u00e9ria de propriedade intelectual.<\/p>\n                        <\/div>\n                    <\/div>\n                <\/div>\n                        <div class=\"accordion-item\">\n                    <h2 class=\"accordion-header\">\n                        <button class=\"accordion-button collapsed gap-3 align-items-start has-text\" type=\"button\" data-bs-toggle=\"collapse\" data-bs-target=\"#flush-4\"  aria-expanded=\"false\" aria-controls=\"flush-4\">\n                            Regulamenta\u00e7\u00e3o                        <\/button>\n                    <\/h2>\n                    <div id=\"flush-4\" class=\"accordion-collapse collapse\" data-bs-parent=\"#accordion-block_75ed5268364843202d17142bbe722d47\">\n                        <div class=\"accordion-body\">\n                            <p>Processos de entrada no mercado, publicidade a medicamentos, processos judiciais e administrativos.<\/p>\n                        <\/div>\n                    <\/div>\n                <\/div>\n                        <div class=\"accordion-item\">\n                    <h2 class=\"accordion-header\">\n                        <button class=\"accordion-button collapsed gap-3 align-items-start has-text\" type=\"button\" data-bs-toggle=\"collapse\" data-bs-target=\"#flush-5\"  aria-expanded=\"false\" aria-controls=\"flush-5\">\n                            Fiscalidade                        <\/button>\n                    <\/h2>\n                    <div id=\"flush-5\" class=\"accordion-collapse collapse\" data-bs-parent=\"#accordion-block_75ed5268364843202d17142bbe722d47\">\n                        <div class=\"accordion-body\">\n                            <p>Tributa\u00e7\u00e3o das sociedades, fiscalidade internacional e quest\u00f5es de propriedade intelectual.<\/p>\n                        <\/div>\n                    <\/div>\n                <\/div>\n                <\/div>\n    <\/div>\n\n<\/div>\n\n\n\n\n<div id=\"TituloTexto-block_020fa98a8297d470e7fabcef138734f2\" class=\"TituloTexto v2\">\n    <div class=\"customContainer right\">\n        <div class=\"textContainer \">\n            <div>\n                                <div class=\"texto\"><p>A nossa abordagem multidisciplinar permite-nos oferecer um aconselhamento coordenado e especializado em todos os subsectores da sa\u00fade, incluindo a biotecnologia, os dispositivos m\u00e9dicos, o saneamento, a fitossanidade e a sa\u00fade animal. Com uma equipa altamente qualificada e especializada, estamos preparados para enfrentar os desafios jur\u00eddicos mais complexos que os nossos clientes enfrentam neste sector em constante evolu\u00e7\u00e3o.<\/p>\n<\/div>\n            <\/div>\n                    <\/div>\n    <\/div>\n<\/div>\n\n\n\n\n<div id=\"AcordeonAreasSectores-block_fd078d2edb60ab9440d5bd1a14c90e27\" class=\"AcordeonAreasSectores\">\n\n    <div class=\"accordion accordion-flush\" id=\"accordion-block_fd078d2edb60ab9440d5bd1a14c90e27\">\n        <div class=\"accordion-item\">\n            <h2 class=\"accordion-header\">\n                <button class=\"accordion-button collapsed gap-3 align-items-start\" type=\"button\" data-bs-toggle=\"collapse\" data-bs-target=\"#flush-block_fd078d2edb60ab9440d5bd1a14c90e27\" aria-expanded=\"false\" aria-controls=\"flush-block_fd078d2edb60ab9440d5bd1a14c90e27\">\n                     \u00c1reas e sectores relacionados:\n                <\/button>\n            <\/h2>\n            <div id=\"flush-block_fd078d2edb60ab9440d5bd1a14c90e27\" class=\"accordion-collapse collapse\" data-bs-parent=\"#accordion-block_fd078d2edb60ab9440d5bd1a14c90e27\">\n                <div class=\"accordion-body\">\n                                            <div class=\"titulo\">\u00c1reas<\/div>\n                                                <div class=\"areas-sectores\">\n                            <div class=\"out\">\n                                                                    <a class=\"item\" href=\"https:\/\/ga-p.com\/pt-pt\/area\/direito-comercial-societario\/\">Comercial, Societ\u00e1rio e M&amp;A<\/a>\n                                                                    <a class=\"item\" href=\"https:\/\/ga-p.com\/pt-pt\/area\/publico-e-sectores-regulados\/\">P\u00fablico e Setores Regulados<\/a>\n                                                            <\/div>\n                                                    <\/div>\n                                                            <\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n\n<\/div>\n\n<\/div>\n<\/div>\n\n<\/div>\n\n    <\/div>\n\n<\/div>\n\n\n\n\n<div id=\"CargosPersonas-block_a9234d253fa0c25d4184a7b5ecf85f6d\" class=\"CargosPersonas egeo\">\n\n    <div class=\"container\">\n        <div class=\"row align-items-end\">\n            <div class=\"col-12 col-lg-6\">\n                <div class=\"title\"><h2 class=''>Conhe\u00e7a a equipa<\/h2>\n<\/div>\n            <\/div>\n            <div class=\"col-12 col-lg-6 selectores\">\n                <div class=\"nav nav-tabs\" id=\"nav-tab\" role=\"tablist\">\n                                            <button class=\"nav-link active\" id=\"grupo-personas-0-tab\" data-bs-toggle=\"tab\" data-bs-target=\"#grupo-personas-0\" type=\"button\" role=\"tab\" aria-controls=\"nav-grupo-personas-0\" aria-selected=\"true\">Contatos<\/button>\n                                            <button class=\"nav-link \" id=\"grupo-personas-1-tab\" data-bs-toggle=\"tab\" data-bs-target=\"#grupo-personas-1\" type=\"button\" role=\"tab\" aria-controls=\"nav-grupo-personas-1\" aria-selected=\"true\">Equipa<\/button>\n                                    <\/div>\n            <\/div>\n        <\/div>\n\n        <div class=\"tab-content\" id=\"nav-tabContent\">\n                                            <div class=\"tab-pane fade show active\" id=\"grupo-personas-0\" role=\"tabpanel\" aria-labelledby=\"grupo-personas-0-tab\" tabindex=\"0\">\n                    <div class=\"itemGrid d-none d-lg-grid\">\n                                                        <div\n        class=\"personaCard  egeo\">\n        <div class=\"personaContent\">\n                            <a href=\"https:\/\/ga-p.com\/pt-pt\/pessoa\/irene-fernandez-puyol\/\">\n                    <div class=\"personaImage\"\n                        style=\"background:url(https:\/\/ga-p.com\/wp-content\/uploads\/2024\/05\/Fondo-personas-nueva-web.webp)\">\n                        <img fetchpriority=\"high\" decoding=\"async\" width=\"424\" height=\"424\" src=\"https:\/\/ga-p.com\/wp-content\/uploads\/2024\/06\/Irene-Fernandez-Puyol.png\" class=\"\" alt=\"Irene Ferna\u0301ndez Puyol\" loading=\"eager\" srcset=\"https:\/\/ga-p.com\/wp-content\/uploads\/2024\/06\/Irene-Fernandez-Puyol.png 424w, https:\/\/ga-p.com\/wp-content\/uploads\/2024\/06\/Irene-Fernandez-Puyol-300x300.png 300w, https:\/\/ga-p.com\/wp-content\/uploads\/2024\/06\/Irene-Fernandez-Puyol-150x150.png 150w\" sizes=\"(max-width: 424px) 100vw, 424px\" \/>                    <\/div>\n                <\/a>\n                        <div class=\"personaInfo\">\n                <a style=\"text-decoration: none;\" href=\"https:\/\/ga-p.com\/pt-pt\/pessoa\/irene-fernandez-puyol\/\">\n                    <div class=\"name\">Irene Ferna\u0301ndez Puyol<\/div>\n                <\/a>\n                                    <div class=\"cargo\">S\u00f3cia<\/div>\n                                                    <div class=\"specs mb-2 d-flex align-items-center gap-2\">\n                                                    <img decoding=\"async\" class=\"image\" alt=\"email\"\n                                src=\"https:\/\/ga-p.com\/wp-content\/themes\/ga-p\/assets\/images\/email-icon.svg\" \/>\n                                                <a href=\"mailto:ifernandez@ga-p.com\">ifernandez@ga-p.com<\/a>\n                    <\/div>\n                                                    <div class=\"specs mb-2 d-flex align-items-center gap-2\">\n                                                    <img decoding=\"async\" class=\"image\" src=\"https:\/\/ga-p.com\/wp-content\/themes\/ga-p\/assets\/images\/profession-icon.svg\" \/>\n                                                <div class=\"areas\">\n                                                            <a\n                                    href=\"https:\/\/ga-p.com\/pt-pt\/area\/publico-e-sectores-regulados\/\">P\u00fablico e Setores Regulados<\/a>\n                                                    <\/div>\n                    <\/div>\n                                                    <div class=\"specs mb-2 d-flex align-items-center gap-2\">\n                                                    <img decoding=\"async\" class=\"image\" src=\"https:\/\/ga-p.com\/wp-content\/themes\/ga-p\/assets\/images\/select-oficinas.svg\" \/>\n                                                <a\n                            href=\"https:\/\/ga-p.com\/pt-pt\/escritorio\/madrid\/\">Madrid<\/a>\n                    <\/div>\n                                                    <div class=\"specs mb-2 d-flex align-items-center gap-2\">\n                                                    <img decoding=\"async\" alt=\"icon\"\n                                src=\"https:\/\/ga-p.com\/wp-content\/themes\/ga-p\/assets\/images\/mobile-primary.svg\" \/>\n                                                <a href=\"tel:(+34) 91 582 91 00\">(+34) 91 582 91 00<\/a>\n                    <\/div>\n                            <\/div>\n        <\/div>\n\n        <a href=\"https:\/\/ga-p.com\/pt-pt\/pessoa\/irene-fernandez-puyol\/\" class=\"align-self-start align-self-lg-end\">\n            <div class=\"openCard\">\n                                    <img decoding=\"async\" alt=\"icon\" src=\"https:\/\/ga-p.com\/wp-content\/themes\/ga-p\/assets\/images\/arrow-open.svg\" \/>\n                    <img decoding=\"async\" alt=\"icon\" src=\"https:\/\/ga-p.com\/wp-content\/themes\/ga-p\/assets\/images\/arrow-open.svg\" \/>\n                \n            <\/div>\n        <\/a>\n    <\/div>\n                                                                    <\/div>\n\n                    <div class=\"d-block d-lg-none\">\n                        <div class=\"swiper swiperCargos swiperGrupo-0\">\n                            <div class=\"swiper-wrapper\">\n                                                                <div class=\"swiper-slide\">\n                                        <div\n        class=\"personaCard  egeo\">\n        <div class=\"personaContent\">\n                            <a href=\"https:\/\/ga-p.com\/pt-pt\/pessoa\/irene-fernandez-puyol\/\">\n                    <div class=\"personaImage\"\n                        style=\"background:url(https:\/\/ga-p.com\/wp-content\/uploads\/2024\/05\/Fondo-personas-nueva-web.webp)\">\n                        <img fetchpriority=\"high\" decoding=\"async\" width=\"424\" height=\"424\" src=\"https:\/\/ga-p.com\/wp-content\/uploads\/2024\/06\/Irene-Fernandez-Puyol.png\" class=\"\" alt=\"Irene Ferna\u0301ndez Puyol\" loading=\"eager\" srcset=\"https:\/\/ga-p.com\/wp-content\/uploads\/2024\/06\/Irene-Fernandez-Puyol.png 424w, https:\/\/ga-p.com\/wp-content\/uploads\/2024\/06\/Irene-Fernandez-Puyol-300x300.png 300w, https:\/\/ga-p.com\/wp-content\/uploads\/2024\/06\/Irene-Fernandez-Puyol-150x150.png 150w\" sizes=\"(max-width: 424px) 100vw, 424px\" \/>                    <\/div>\n                <\/a>\n                        <div class=\"personaInfo\">\n                <a style=\"text-decoration: none;\" href=\"https:\/\/ga-p.com\/pt-pt\/pessoa\/irene-fernandez-puyol\/\">\n                    <div class=\"name\">Irene Ferna\u0301ndez Puyol<\/div>\n                <\/a>\n                                    <div class=\"cargo\">S\u00f3cia<\/div>\n                                                    <div class=\"specs mb-2 d-flex align-items-center gap-2\">\n                                                    <img decoding=\"async\" class=\"image\" alt=\"email\"\n                                src=\"https:\/\/ga-p.com\/wp-content\/themes\/ga-p\/assets\/images\/email-icon.svg\" \/>\n                                                <a href=\"mailto:ifernandez@ga-p.com\">ifernandez@ga-p.com<\/a>\n                    <\/div>\n                                                    <div class=\"specs mb-2 d-flex align-items-center gap-2\">\n                                                    <img decoding=\"async\" class=\"image\" src=\"https:\/\/ga-p.com\/wp-content\/themes\/ga-p\/assets\/images\/profession-icon.svg\" \/>\n                                                <div class=\"areas\">\n                                                            <a\n                                    href=\"https:\/\/ga-p.com\/pt-pt\/area\/publico-e-sectores-regulados\/\">P\u00fablico e Setores Regulados<\/a>\n                                                    <\/div>\n                    <\/div>\n                                                    <div class=\"specs mb-2 d-flex align-items-center gap-2\">\n                                                    <img decoding=\"async\" class=\"image\" src=\"https:\/\/ga-p.com\/wp-content\/themes\/ga-p\/assets\/images\/select-oficinas.svg\" \/>\n                                                <a\n                            href=\"https:\/\/ga-p.com\/pt-pt\/escritorio\/madrid\/\">Madrid<\/a>\n                    <\/div>\n                                                    <div class=\"specs mb-2 d-flex align-items-center gap-2\">\n                                                    <img decoding=\"async\" alt=\"icon\"\n                                src=\"https:\/\/ga-p.com\/wp-content\/themes\/ga-p\/assets\/images\/mobile-primary.svg\" \/>\n                                                <a href=\"tel:(+34) 91 582 91 00\">(+34) 91 582 91 00<\/a>\n                    <\/div>\n                            <\/div>\n        <\/div>\n\n        <a href=\"https:\/\/ga-p.com\/pt-pt\/pessoa\/irene-fernandez-puyol\/\" class=\"align-self-start align-self-lg-end\">\n            <div class=\"openCard\">\n                                    <img decoding=\"async\" alt=\"icon\" src=\"https:\/\/ga-p.com\/wp-content\/themes\/ga-p\/assets\/images\/arrow-open.svg\" \/>\n                    <img decoding=\"async\" alt=\"icon\" src=\"https:\/\/ga-p.com\/wp-content\/themes\/ga-p\/assets\/images\/arrow-open.svg\" \/>\n                \n            <\/div>\n        <\/a>\n    <\/div>\n                                <\/div>\n                                                            <\/div>\n                            <div class=\"swiperPagination mt-3\">\n                                <div class=\"container\">\n                                    <div class=\"row\">\n                                        <div class=\"col-6\">\n                                            <div class=\"swiperBullets\"><\/div>\n                                        <\/div>\n                                        <div class=\"col-6 swiperArrowsMobile\">\n                                            <div class=\"swiperCargosArrows swiperArrows\">\n                                                <div class=\"d-flex align-items-center gap-4 justify-content-end\">\n                                                    <div class=\"swiper-button-prev\"><img decoding=\"async\" alt=\"icon\" src=\"https:\/\/ga-p.com\/wp-content\/themes\/ga-p\/assets\/images\/slider-arrow.svg\" \/><\/div>\n                                                    <div class=\"swiper-button-next\"><img decoding=\"async\" alt=\"icon\" src=\"https:\/\/ga-p.com\/wp-content\/themes\/ga-p\/assets\/images\/slider-arrow.svg\" \/><\/div>\n                                                <\/div>\n                                            <\/div>\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div>\n                        <\/div>\n                    <\/div>\n                <\/div>\n            <script>\n                jQuery(document).ready(function ($){\n                    var swiperPersGrupo_0 = new Swiper(\".CargosPersonas .swiperCargos.swiperGrupo-0\", {\n                        slidesPerView: 1,\n                        spaceBetween: 24,\n                        navigation: {\n                            nextEl: \".CargosPersonas .swiperGrupo-0 .swiperArrows .swiper-button-next\",\n                            prevEl: \".CargosPersonas .swiperGrupo-0 .swiperArrows .swiper-button-prev\",\n                        },\n                        pagination: {\n                            el: '.CargosPersonas .swiperGrupo-0 .swiperBullets',\n                            clickable: true,\n                            type: $.fn.isMobileViewport() ? 'fraction' : 'bullets',\n                            formatFractionCurrent: function (number) { return ('0' + number).slice(-2); },\n                            formatFractionTotal: function (number) { return ('0' + number).slice(-2); },\n                            renderFraction: function (currentClass, totalClass) {\n                                return '<span class=\"swiper-pagination-fraction ' + currentClass + '\"><\/span>' +\n                                    ' \/ ' +\n                                    '<span class=\"swiper-pagination-fraction ' + totalClass + '\"><\/span>';\n                            }\n                        },\n                    });\n                })\n            <\/script>\n                                            <div class=\"tab-pane fade \" id=\"grupo-personas-1\" role=\"tabpanel\" aria-labelledby=\"grupo-personas-1-tab\" tabindex=\"0\">\n                    <div class=\"itemGrid d-none d-lg-grid\">\n                                                        <div\n        class=\"personaCard  egeo\">\n        <div class=\"personaContent\">\n                            <a href=\"https:\/\/ga-p.com\/pt-pt\/pessoa\/daniel-marin\/\">\n                    <div class=\"personaImage\"\n                        style=\"background:url(https:\/\/ga-p.com\/wp-content\/uploads\/2024\/05\/Fondo-personas-nueva-web.webp)\">\n                        <img decoding=\"async\" width=\"424\" height=\"424\" src=\"https:\/\/ga-p.com\/wp-content\/uploads\/2024\/06\/Daniel-Marin.png\" class=\"\" alt=\"Daniel Mar\u00edn\" loading=\"eager\" srcset=\"https:\/\/ga-p.com\/wp-content\/uploads\/2024\/06\/Daniel-Marin.png 424w, https:\/\/ga-p.com\/wp-content\/uploads\/2024\/06\/Daniel-Marin-300x300.png 300w, https:\/\/ga-p.com\/wp-content\/uploads\/2024\/06\/Daniel-Marin-150x150.png 150w\" sizes=\"(max-width: 424px) 100vw, 424px\" \/>                    <\/div>\n                <\/a>\n                        <div class=\"personaInfo\">\n                <a style=\"text-decoration: none;\" href=\"https:\/\/ga-p.com\/pt-pt\/pessoa\/daniel-marin\/\">\n                    <div class=\"name\">Daniel Mar\u00edn<\/div>\n                <\/a>\n                                    <div class=\"cargo\">S\u00f3cio<\/div>\n                                                    <div class=\"specs mb-2 d-flex align-items-center gap-2\">\n                                                    <img decoding=\"async\" class=\"image\" alt=\"email\"\n                                src=\"https:\/\/ga-p.com\/wp-content\/themes\/ga-p\/assets\/images\/email-icon.svg\" \/>\n                                                <a href=\"mailto:dmarin@ga-p.com\">dmarin@ga-p.com<\/a>\n                    <\/div>\n                                                    <div class=\"specs mb-2 d-flex align-items-center gap-2\">\n                                                    <img decoding=\"async\" class=\"image\" src=\"https:\/\/ga-p.com\/wp-content\/themes\/ga-p\/assets\/images\/profession-icon.svg\" \/>\n                                                <div class=\"areas\">\n                                                            <a\n                                    href=\"https:\/\/ga-p.com\/pt-pt\/area\/direito-comercial-societario\/\">Comercial, Societ\u00e1rio e M&amp;A, <\/a>\n                                                            <a\n                                    href=\"https:\/\/ga-p.com\/pt-pt\/area\/sustentabilidade\/\">Sustentabilidade<\/a>\n                                                    <\/div>\n                    <\/div>\n                                                    <div class=\"specs mb-2 d-flex align-items-center gap-2\">\n                                                    <img decoding=\"async\" class=\"image\" src=\"https:\/\/ga-p.com\/wp-content\/themes\/ga-p\/assets\/images\/select-oficinas.svg\" \/>\n                                                <a\n                            href=\"https:\/\/ga-p.com\/pt-pt\/escritorio\/barcelona\/\">Barcelona<\/a>\n                    <\/div>\n                                                    <div class=\"specs mb-2 d-flex align-items-center gap-2\">\n                                                    <img decoding=\"async\" alt=\"icon\"\n                                src=\"https:\/\/ga-p.com\/wp-content\/themes\/ga-p\/assets\/images\/mobile-primary.svg\" \/>\n                                                <a href=\"tel:(+34) 93 415 74 00\">(+34) 93 415 74 00<\/a>\n                    <\/div>\n                            <\/div>\n        <\/div>\n\n        <a href=\"https:\/\/ga-p.com\/pt-pt\/pessoa\/daniel-marin\/\" class=\"align-self-start align-self-lg-end\">\n            <div class=\"openCard\">\n                                    <img decoding=\"async\" alt=\"icon\" src=\"https:\/\/ga-p.com\/wp-content\/themes\/ga-p\/assets\/images\/arrow-open.svg\" \/>\n                    <img decoding=\"async\" alt=\"icon\" src=\"https:\/\/ga-p.com\/wp-content\/themes\/ga-p\/assets\/images\/arrow-open.svg\" \/>\n                \n            <\/div>\n        <\/a>\n    <\/div>\n                                                        <div\n        class=\"personaCard  egeo\">\n        <div class=\"personaContent\">\n                            <a href=\"https:\/\/ga-p.com\/pt-pt\/pessoa\/estibaliz-aranburu\/\">\n                    <div class=\"personaImage\"\n                        style=\"background:url(https:\/\/ga-p.com\/wp-content\/uploads\/2024\/05\/Fondo-personas-nueva-web.webp)\">\n                        <img decoding=\"async\" width=\"424\" height=\"424\" src=\"https:\/\/ga-p.com\/wp-content\/uploads\/2024\/06\/Estibaliz-Aranburu.png\" class=\"\" alt=\"Estibaliz Aranburu\" loading=\"eager\" srcset=\"https:\/\/ga-p.com\/wp-content\/uploads\/2024\/06\/Estibaliz-Aranburu.png 424w, https:\/\/ga-p.com\/wp-content\/uploads\/2024\/06\/Estibaliz-Aranburu-300x300.png 300w, https:\/\/ga-p.com\/wp-content\/uploads\/2024\/06\/Estibaliz-Aranburu-150x150.png 150w\" sizes=\"(max-width: 424px) 100vw, 424px\" \/>                    <\/div>\n                <\/a>\n                        <div class=\"personaInfo\">\n                <a style=\"text-decoration: none;\" href=\"https:\/\/ga-p.com\/pt-pt\/pessoa\/estibaliz-aranburu\/\">\n                    <div class=\"name\">Estibaliz Aranburu<\/div>\n                <\/a>\n                                    <div class=\"cargo\">S\u00f3cia<\/div>\n                                                    <div class=\"specs mb-2 d-flex align-items-center gap-2\">\n                                                    <img decoding=\"async\" class=\"image\" alt=\"email\"\n                                src=\"https:\/\/ga-p.com\/wp-content\/themes\/ga-p\/assets\/images\/email-icon.svg\" \/>\n                                                <a href=\"mailto:earanburu@ga-p.com\">earanburu@ga-p.com<\/a>\n                    <\/div>\n                                                    <div class=\"specs mb-2 d-flex align-items-center gap-2\">\n                                                    <img decoding=\"async\" class=\"image\" src=\"https:\/\/ga-p.com\/wp-content\/themes\/ga-p\/assets\/images\/profession-icon.svg\" \/>\n                                                <div class=\"areas\">\n                                                            <a\n                                    href=\"https:\/\/ga-p.com\/pt-pt\/area\/direito-comercial-societario\/\">Comercial, Societ\u00e1rio e M&amp;A, <\/a>\n                                                            <a\n                                    href=\"https:\/\/ga-p.com\/pt-pt\/area\/sustentabilidade\/\">Sustentabilidade<\/a>\n                                                    <\/div>\n                    <\/div>\n                                                    <div class=\"specs mb-2 d-flex align-items-center gap-2\">\n                                                    <img decoding=\"async\" class=\"image\" src=\"https:\/\/ga-p.com\/wp-content\/themes\/ga-p\/assets\/images\/select-oficinas.svg\" \/>\n                                                <a\n                            href=\"https:\/\/ga-p.com\/pt-pt\/escritorio\/bilbau\/\">Bilbau<\/a>\n                    <\/div>\n                                                    <div class=\"specs mb-2 d-flex align-items-center gap-2\">\n                                                    <img decoding=\"async\" alt=\"icon\"\n                                src=\"https:\/\/ga-p.com\/wp-content\/themes\/ga-p\/assets\/images\/mobile-primary.svg\" \/>\n                                                <a href=\"tel:(+34) 94 415 70 15\">(+34) 94 415 70 15<\/a>\n                    <\/div>\n                            <\/div>\n        <\/div>\n\n        <a href=\"https:\/\/ga-p.com\/pt-pt\/pessoa\/estibaliz-aranburu\/\" class=\"align-self-start align-self-lg-end\">\n            <div class=\"openCard\">\n                                    <img decoding=\"async\" alt=\"icon\" src=\"https:\/\/ga-p.com\/wp-content\/themes\/ga-p\/assets\/images\/arrow-open.svg\" \/>\n                    <img decoding=\"async\" alt=\"icon\" src=\"https:\/\/ga-p.com\/wp-content\/themes\/ga-p\/assets\/images\/arrow-open.svg\" \/>\n                \n            <\/div>\n        <\/a>\n    <\/div>\n                                                        <div\n        class=\"personaCard  egeo\">\n        <div class=\"personaContent\">\n                            <a href=\"https:\/\/ga-p.com\/pt-pt\/pessoa\/jesus-ibanez\/\">\n                    <div class=\"personaImage\"\n                        style=\"background:url(https:\/\/ga-p.com\/wp-content\/uploads\/2024\/05\/Fondo-personas-nueva-web.webp)\">\n                        <img decoding=\"async\" width=\"424\" height=\"424\" src=\"https:\/\/ga-p.com\/wp-content\/uploads\/2024\/06\/Jesus-Ibanez.png\" class=\"\" alt=\"Jes\u00fas Iba\u00f1ez\" loading=\"eager\" srcset=\"https:\/\/ga-p.com\/wp-content\/uploads\/2024\/06\/Jesus-Ibanez.png 424w, https:\/\/ga-p.com\/wp-content\/uploads\/2024\/06\/Jesus-Ibanez-300x300.png 300w, https:\/\/ga-p.com\/wp-content\/uploads\/2024\/06\/Jesus-Ibanez-150x150.png 150w\" sizes=\"(max-width: 424px) 100vw, 424px\" \/>                    <\/div>\n                <\/a>\n                        <div class=\"personaInfo\">\n                <a style=\"text-decoration: none;\" href=\"https:\/\/ga-p.com\/pt-pt\/pessoa\/jesus-ibanez\/\">\n                    <div class=\"name\">Jes\u00fas Iba\u00f1ez<\/div>\n                <\/a>\n                                    <div class=\"cargo\">S\u00f3cio<\/div>\n                                                    <div class=\"specs mb-2 d-flex align-items-center gap-2\">\n                                                    <img decoding=\"async\" class=\"image\" alt=\"email\"\n                                src=\"https:\/\/ga-p.com\/wp-content\/themes\/ga-p\/assets\/images\/email-icon.svg\" \/>\n                                                <a href=\"mailto:jibanez@ga-p.com\">jibanez@ga-p.com<\/a>\n                    <\/div>\n                                                    <div class=\"specs mb-2 d-flex align-items-center gap-2\">\n                                                    <img decoding=\"async\" class=\"image\" src=\"https:\/\/ga-p.com\/wp-content\/themes\/ga-p\/assets\/images\/profession-icon.svg\" \/>\n                                                <div class=\"areas\">\n                                                            <a\n                                    href=\"https:\/\/ga-p.com\/pt-pt\/area\/direito-comercial-societario\/\">Comercial, Societ\u00e1rio e M&amp;A<\/a>\n                                                    <\/div>\n                    <\/div>\n                                                    <div class=\"specs mb-2 d-flex align-items-center gap-2\">\n                                                    <img decoding=\"async\" class=\"image\" src=\"https:\/\/ga-p.com\/wp-content\/themes\/ga-p\/assets\/images\/select-oficinas.svg\" \/>\n                                                <a\n                            href=\"https:\/\/ga-p.com\/pt-pt\/escritorio\/valencia\/\">Val\u00eancia<\/a>\n                    <\/div>\n                                                    <div class=\"specs mb-2 d-flex align-items-center gap-2\">\n                                                    <img decoding=\"async\" alt=\"icon\"\n                                src=\"https:\/\/ga-p.com\/wp-content\/themes\/ga-p\/assets\/images\/mobile-primary.svg\" \/>\n                                                <a href=\"tel:(+34) 96 351 38 35\">(+34) 96 351 38 35<\/a>\n                    <\/div>\n                            <\/div>\n        <\/div>\n\n        <a href=\"https:\/\/ga-p.com\/pt-pt\/pessoa\/jesus-ibanez\/\" class=\"align-self-start align-self-lg-end\">\n            <div class=\"openCard\">\n                                    <img decoding=\"async\" alt=\"icon\" src=\"https:\/\/ga-p.com\/wp-content\/themes\/ga-p\/assets\/images\/arrow-open.svg\" \/>\n                    <img decoding=\"async\" alt=\"icon\" src=\"https:\/\/ga-p.com\/wp-content\/themes\/ga-p\/assets\/images\/arrow-open.svg\" \/>\n                \n            <\/div>\n        <\/a>\n    <\/div>\n                                                        <div\n        class=\"personaCard  egeo\">\n        <div class=\"personaContent\">\n                            <a href=\"https:\/\/ga-p.com\/pt-pt\/pessoa\/santiago-garrido-de-las-heras\/\">\n                    <div class=\"personaImage\"\n                        style=\"background:url(https:\/\/ga-p.com\/wp-content\/uploads\/2024\/05\/Fondo-personas-nueva-web.webp)\">\n                        <img decoding=\"async\" width=\"424\" height=\"424\" src=\"https:\/\/ga-p.com\/wp-content\/uploads\/2024\/06\/Santiago-Garrido.png\" class=\"\" alt=\"Santiago Garrido de las Heras\" loading=\"eager\" srcset=\"https:\/\/ga-p.com\/wp-content\/uploads\/2024\/06\/Santiago-Garrido.png 424w, https:\/\/ga-p.com\/wp-content\/uploads\/2024\/06\/Santiago-Garrido-300x300.png 300w, https:\/\/ga-p.com\/wp-content\/uploads\/2024\/06\/Santiago-Garrido-150x150.png 150w\" sizes=\"(max-width: 424px) 100vw, 424px\" \/>                    <\/div>\n                <\/a>\n                        <div class=\"personaInfo\">\n                <a style=\"text-decoration: none;\" href=\"https:\/\/ga-p.com\/pt-pt\/pessoa\/santiago-garrido-de-las-heras\/\">\n                    <div class=\"name\">Santiago Garrido de las Heras<\/div>\n                <\/a>\n                                    <div class=\"cargo\">S\u00f3cio<\/div>\n                                                    <div class=\"specs mb-2 d-flex align-items-center gap-2\">\n                                                    <img decoding=\"async\" class=\"image\" alt=\"email\"\n                                src=\"https:\/\/ga-p.com\/wp-content\/themes\/ga-p\/assets\/images\/email-icon.svg\" \/>\n                                                <a href=\"mailto:sgarrido@ga-p.com\">sgarrido@ga-p.com<\/a>\n                    <\/div>\n                                                    <div class=\"specs mb-2 d-flex align-items-center gap-2\">\n                                                    <img decoding=\"async\" class=\"image\" src=\"https:\/\/ga-p.com\/wp-content\/themes\/ga-p\/assets\/images\/profession-icon.svg\" \/>\n                                                <div class=\"areas\">\n                                                            <a\n                                    href=\"https:\/\/ga-p.com\/pt-pt\/area\/meio-ambiente\/\">Meio Ambiente, <\/a>\n                                                            <a\n                                    href=\"https:\/\/ga-p.com\/pt-pt\/area\/publico-e-sectores-regulados\/\">P\u00fablico e Setores Regulados, <\/a>\n                                                            <a\n                                    href=\"https:\/\/ga-p.com\/pt-pt\/area\/sustentabilidade\/\">Sustentabilidade<\/a>\n                                                    <\/div>\n                    <\/div>\n                                                    <div class=\"specs mb-2 d-flex align-items-center gap-2\">\n                                                    <img decoding=\"async\" class=\"image\" src=\"https:\/\/ga-p.com\/wp-content\/themes\/ga-p\/assets\/images\/select-oficinas.svg\" \/>\n                                                <a\n                            href=\"https:\/\/ga-p.com\/pt-pt\/escritorio\/madrid\/\">Madrid<\/a>\n                    <\/div>\n                                                    <div class=\"specs mb-2 d-flex align-items-center gap-2\">\n                                                    <img decoding=\"async\" alt=\"icon\"\n                                src=\"https:\/\/ga-p.com\/wp-content\/themes\/ga-p\/assets\/images\/mobile-primary.svg\" \/>\n                                                <a href=\"tel:(+34) 91 582 91 00\">(+34) 91 582 91 00<\/a>\n                    <\/div>\n                            <\/div>\n        <\/div>\n\n        <a href=\"https:\/\/ga-p.com\/pt-pt\/pessoa\/santiago-garrido-de-las-heras\/\" class=\"align-self-start align-self-lg-end\">\n            <div class=\"openCard\">\n                                    <img decoding=\"async\" alt=\"icon\" src=\"https:\/\/ga-p.com\/wp-content\/themes\/ga-p\/assets\/images\/arrow-open.svg\" \/>\n                    <img decoding=\"async\" alt=\"icon\" src=\"https:\/\/ga-p.com\/wp-content\/themes\/ga-p\/assets\/images\/arrow-open.svg\" \/>\n                \n            <\/div>\n        <\/a>\n    <\/div>\n                                                        <div\n        class=\"personaCard  egeo\">\n        <div class=\"personaContent\">\n                            <a href=\"https:\/\/ga-p.com\/pt-pt\/pessoa\/eduardo-gomez-de-la-cruz\/\">\n                    <div class=\"personaImage\"\n                        style=\"background:url(https:\/\/ga-p.com\/wp-content\/uploads\/2024\/05\/Fondo-personas-nueva-web.webp)\">\n                        <img decoding=\"async\" width=\"424\" height=\"424\" src=\"https:\/\/ga-p.com\/wp-content\/uploads\/2024\/06\/Eduardo-Gomez-de-la-Cruz.png\" class=\"\" alt=\"Eduardo G\u00f3mez de la Cruz\" loading=\"eager\" srcset=\"https:\/\/ga-p.com\/wp-content\/uploads\/2024\/06\/Eduardo-Gomez-de-la-Cruz.png 424w, https:\/\/ga-p.com\/wp-content\/uploads\/2024\/06\/Eduardo-Gomez-de-la-Cruz-300x300.png 300w, https:\/\/ga-p.com\/wp-content\/uploads\/2024\/06\/Eduardo-Gomez-de-la-Cruz-150x150.png 150w\" sizes=\"(max-width: 424px) 100vw, 424px\" \/>                    <\/div>\n                <\/a>\n                        <div class=\"personaInfo\">\n                <a style=\"text-decoration: none;\" href=\"https:\/\/ga-p.com\/pt-pt\/pessoa\/eduardo-gomez-de-la-cruz\/\">\n                    <div class=\"name\">Eduardo G\u00f3mez de la Cruz<\/div>\n                <\/a>\n                                    <div class=\"cargo\">Counsel<\/div>\n                                                    <div class=\"specs mb-2 d-flex align-items-center gap-2\">\n                                                    <img decoding=\"async\" class=\"image\" alt=\"email\"\n                                src=\"https:\/\/ga-p.com\/wp-content\/themes\/ga-p\/assets\/images\/email-icon.svg\" \/>\n                                                <a href=\"mailto:e.gomez@ga-p.com\">e.gomez@ga-p.com<\/a>\n                    <\/div>\n                                                    <div class=\"specs mb-2 d-flex align-items-center gap-2\">\n                                                    <img decoding=\"async\" class=\"image\" src=\"https:\/\/ga-p.com\/wp-content\/themes\/ga-p\/assets\/images\/profession-icon.svg\" \/>\n                                                <div class=\"areas\">\n                                                            <a\n                                    href=\"https:\/\/ga-p.com\/pt-pt\/area\/concorrencia-e-direito-da-uniao-europeia\/\">Concorr\u00eancia e Direito da Uni\u00e3o Europeia<\/a>\n                                                    <\/div>\n                    <\/div>\n                                                    <div class=\"specs mb-2 d-flex align-items-center gap-2\">\n                                                    <img decoding=\"async\" class=\"image\" src=\"https:\/\/ga-p.com\/wp-content\/themes\/ga-p\/assets\/images\/select-oficinas.svg\" \/>\n                                                <a\n                            href=\"https:\/\/ga-p.com\/pt-pt\/escritorio\/madrid\/\">Madrid<\/a>\n                    <\/div>\n                                                    <div class=\"specs mb-2 d-flex align-items-center gap-2\">\n                                                    <img decoding=\"async\" alt=\"icon\"\n                                src=\"https:\/\/ga-p.com\/wp-content\/themes\/ga-p\/assets\/images\/mobile-primary.svg\" \/>\n                                                <a href=\"tel:(+34) 91 582 91 00\">(+34) 91 582 91 00<\/a>\n                    <\/div>\n                            <\/div>\n        <\/div>\n\n        <a href=\"https:\/\/ga-p.com\/pt-pt\/pessoa\/eduardo-gomez-de-la-cruz\/\" class=\"align-self-start align-self-lg-end\">\n            <div class=\"openCard\">\n                                    <img decoding=\"async\" alt=\"icon\" src=\"https:\/\/ga-p.com\/wp-content\/themes\/ga-p\/assets\/images\/arrow-open.svg\" \/>\n                    <img decoding=\"async\" alt=\"icon\" src=\"https:\/\/ga-p.com\/wp-content\/themes\/ga-p\/assets\/images\/arrow-open.svg\" \/>\n                \n            <\/div>\n        <\/a>\n    <\/div>\n                                                        <div\n        class=\"personaCard  noDetail egeo\">\n        <div class=\"personaContent\">\n                            <div class=\"personaImage expandCardTrigger\"\n                    style=\"background:url(https:\/\/ga-p.com\/wp-content\/uploads\/2024\/05\/Fondo-personas-nueva-web.webp)\">\n                    <img decoding=\"async\" width=\"424\" height=\"424\" src=\"https:\/\/ga-p.com\/wp-content\/uploads\/2024\/06\/Angel-Garcia-2.png\" class=\"\" alt=\"\u00c1ngel Garc\u00eda Vidal\" loading=\"eager\" srcset=\"https:\/\/ga-p.com\/wp-content\/uploads\/2024\/06\/Angel-Garcia-2.png 424w, https:\/\/ga-p.com\/wp-content\/uploads\/2024\/06\/Angel-Garcia-2-300x300.png 300w, https:\/\/ga-p.com\/wp-content\/uploads\/2024\/06\/Angel-Garcia-2-150x150.png 150w\" sizes=\"(max-width: 424px) 100vw, 424px\" \/>                <\/div>\n                        <div class=\"personaInfo\">\n                <div class=\"name expandCardTrigger\">\u00c1ngel Garc\u00eda Vidal<\/div>\n                                    <div class=\"cargo\">Conselho acad\u00e9mico<\/div>\n                                <div class=\"specsCont\">\n                                            <div class=\"specs mb-2 d-flex align-items-center gap-2\">\n                                                            <img decoding=\"async\" class=\"image\" alt=\"email\"\n                                    src=\"https:\/\/ga-p.com\/wp-content\/themes\/ga-p\/assets\/images\/email-icon.svg\" \/>\n                                                        <a href=\"mailto:agarciav@ga-p.com\">agarciav@ga-p.com<\/a>\n                        <\/div>\n                                                                <div class=\"specs mb-2 d-flex align-items-center gap-2\">\n                                                            <img decoding=\"async\" class=\"image\"\n                                    src=\"https:\/\/ga-p.com\/wp-content\/themes\/ga-p\/assets\/images\/select-oficinas.svg\" \/>\n                                                        <a href=\"tel:(+34) 91 582 91 00\">Madrid<\/a>\n                        <\/div>\n                                    <\/div>\n            <\/div>\n            <div class=\"personaExtraInfo\" style=\"display: none\">\n                <div class=\"sectoresAreas w-100\">\n                                            <div class=\"areas\">\n                                                            <a\n                                    href=\"https:\/\/ga-p.com\/pt-pt\/area\/direito-comercial-societario\/\">Comercial, Societ\u00e1rio e M&amp;A, <\/a>\n                                                            <a\n                                    href=\"https:\/\/ga-p.com\/pt-pt\/area\/propiedad-industrial-intelectual\/\">Propriedade Industrial e Intelectual<\/a>\n                                                    <\/div>\n                                    <\/div>\n            <\/div>\n        <\/div>\n                                    <img decoding=\"async\" class=\"expandCard align-self-start align-self-lg-end\" alt=\"icon\"\n                    src=\"https:\/\/ga-p.com\/wp-content\/themes\/ga-p\/assets\/images\/expand-card.svg\" \/>\n                <img decoding=\"async\" class=\"collapseCard align-self-start align-self-lg-end\" alt=\"icon\"\n                    src=\"https:\/\/ga-p.com\/wp-content\/themes\/ga-p\/assets\/images\/collapse-card.svg\" \/>\n                        <\/div>\n\n                                                        <div\n        class=\"personaCard d-none egeo\">\n        <div class=\"personaContent\">\n                            <a href=\"https:\/\/ga-p.com\/pt-pt\/pessoa\/nuria-ribera\/\">\n                    <div class=\"personaImage\"\n                        style=\"background:url(https:\/\/ga-p.com\/wp-content\/uploads\/2024\/05\/Fondo-personas-nueva-web.webp)\">\n                        <img decoding=\"async\" width=\"424\" height=\"424\" src=\"https:\/\/ga-p.com\/wp-content\/uploads\/2024\/06\/Nuria-Ribera.png\" class=\"\" alt=\"N\u00faria Ribera\" loading=\"eager\" srcset=\"https:\/\/ga-p.com\/wp-content\/uploads\/2024\/06\/Nuria-Ribera.png 424w, https:\/\/ga-p.com\/wp-content\/uploads\/2024\/06\/Nuria-Ribera-300x300.png 300w, https:\/\/ga-p.com\/wp-content\/uploads\/2024\/06\/Nuria-Ribera-150x150.png 150w\" sizes=\"(max-width: 424px) 100vw, 424px\" \/>                    <\/div>\n                <\/a>\n                        <div class=\"personaInfo\">\n                <a style=\"text-decoration: none;\" href=\"https:\/\/ga-p.com\/pt-pt\/pessoa\/nuria-ribera\/\">\n                    <div class=\"name\">N\u00faria Ribera<\/div>\n                <\/a>\n                                    <div class=\"cargo\">Associada s\u00e9nior<\/div>\n                                                    <div class=\"specs mb-2 d-flex align-items-center gap-2\">\n                                                    <img decoding=\"async\" class=\"image\" alt=\"email\"\n                                src=\"https:\/\/ga-p.com\/wp-content\/themes\/ga-p\/assets\/images\/email-icon.svg\" \/>\n                                                <a href=\"mailto:nribera@ga-p.com\">nribera@ga-p.com<\/a>\n                    <\/div>\n                                                    <div class=\"specs mb-2 d-flex align-items-center gap-2\">\n                                                    <img decoding=\"async\" class=\"image\" src=\"https:\/\/ga-p.com\/wp-content\/themes\/ga-p\/assets\/images\/profession-icon.svg\" \/>\n                                                <div class=\"areas\">\n                                                            <a\n                                    href=\"https:\/\/ga-p.com\/pt-pt\/area\/propiedad-industrial-intelectual\/\">Propriedade Industrial e Intelectual<\/a>\n                                                    <\/div>\n                    <\/div>\n                                                    <div class=\"specs mb-2 d-flex align-items-center gap-2\">\n                                                    <img decoding=\"async\" class=\"image\" src=\"https:\/\/ga-p.com\/wp-content\/themes\/ga-p\/assets\/images\/select-oficinas.svg\" \/>\n                                                <a\n                            href=\"https:\/\/ga-p.com\/pt-pt\/escritorio\/barcelona\/\">Barcelona<\/a>\n                    <\/div>\n                                                    <div class=\"specs mb-2 d-flex align-items-center gap-2\">\n                                                    <img decoding=\"async\" alt=\"icon\"\n                                src=\"https:\/\/ga-p.com\/wp-content\/themes\/ga-p\/assets\/images\/mobile-primary.svg\" \/>\n                                                <a href=\"tel:(+34) 93 415 74 00\">(+34) 93 415 74 00<\/a>\n                    <\/div>\n                            <\/div>\n        <\/div>\n\n        <a href=\"https:\/\/ga-p.com\/pt-pt\/pessoa\/nuria-ribera\/\" class=\"align-self-start align-self-lg-end\">\n            <div class=\"openCard\">\n                                    <img decoding=\"async\" alt=\"icon\" src=\"https:\/\/ga-p.com\/wp-content\/themes\/ga-p\/assets\/images\/arrow-open.svg\" \/>\n                    <img decoding=\"async\" alt=\"icon\" src=\"https:\/\/ga-p.com\/wp-content\/themes\/ga-p\/assets\/images\/arrow-open.svg\" \/>\n                \n            <\/div>\n        <\/a>\n    <\/div>\n                                                                            <div class=\"cargar_mas\">\n                                Carregar mais                                <img decoding=\"async\" class=\"expandCard align-self-start align-self-lg-end\" alt=\"icon\" src=\"https:\/\/ga-p.com\/wp-content\/themes\/ga-p\/assets\/images\/expand-card.svg\" \/>\n                            <\/div>\n                                            <\/div>\n\n                    <div class=\"d-block d-lg-none\">\n                        <div class=\"swiper swiperCargos swiperGrupo-0\">\n                            <div class=\"swiper-wrapper\">\n                                                                <div class=\"swiper-slide\">\n                                        <div\n        class=\"personaCard  egeo\">\n        <div class=\"personaContent\">\n                            <a href=\"https:\/\/ga-p.com\/pt-pt\/pessoa\/daniel-marin\/\">\n                    <div class=\"personaImage\"\n                        style=\"background:url(https:\/\/ga-p.com\/wp-content\/uploads\/2024\/05\/Fondo-personas-nueva-web.webp)\">\n                        <img decoding=\"async\" width=\"424\" height=\"424\" src=\"https:\/\/ga-p.com\/wp-content\/uploads\/2024\/06\/Daniel-Marin.png\" class=\"\" alt=\"Daniel Mar\u00edn\" loading=\"eager\" srcset=\"https:\/\/ga-p.com\/wp-content\/uploads\/2024\/06\/Daniel-Marin.png 424w, https:\/\/ga-p.com\/wp-content\/uploads\/2024\/06\/Daniel-Marin-300x300.png 300w, https:\/\/ga-p.com\/wp-content\/uploads\/2024\/06\/Daniel-Marin-150x150.png 150w\" sizes=\"(max-width: 424px) 100vw, 424px\" \/>                    <\/div>\n                <\/a>\n                        <div class=\"personaInfo\">\n                <a style=\"text-decoration: none;\" href=\"https:\/\/ga-p.com\/pt-pt\/pessoa\/daniel-marin\/\">\n                    <div class=\"name\">Daniel Mar\u00edn<\/div>\n                <\/a>\n                                    <div class=\"cargo\">S\u00f3cio<\/div>\n                                                    <div class=\"specs mb-2 d-flex align-items-center gap-2\">\n                                                    <img decoding=\"async\" class=\"image\" alt=\"email\"\n                                src=\"https:\/\/ga-p.com\/wp-content\/themes\/ga-p\/assets\/images\/email-icon.svg\" \/>\n                                                <a href=\"mailto:dmarin@ga-p.com\">dmarin@ga-p.com<\/a>\n                    <\/div>\n                                                    <div class=\"specs mb-2 d-flex align-items-center gap-2\">\n                                                    <img decoding=\"async\" class=\"image\" src=\"https:\/\/ga-p.com\/wp-content\/themes\/ga-p\/assets\/images\/profession-icon.svg\" \/>\n                                                <div class=\"areas\">\n                                                            <a\n                                    href=\"https:\/\/ga-p.com\/pt-pt\/area\/direito-comercial-societario\/\">Comercial, Societ\u00e1rio e M&amp;A, <\/a>\n                                                            <a\n                                    href=\"https:\/\/ga-p.com\/pt-pt\/area\/sustentabilidade\/\">Sustentabilidade<\/a>\n                                                    <\/div>\n                    <\/div>\n                                                    <div class=\"specs mb-2 d-flex align-items-center gap-2\">\n                                                    <img decoding=\"async\" class=\"image\" src=\"https:\/\/ga-p.com\/wp-content\/themes\/ga-p\/assets\/images\/select-oficinas.svg\" \/>\n                                                <a\n                            href=\"https:\/\/ga-p.com\/pt-pt\/escritorio\/barcelona\/\">Barcelona<\/a>\n                    <\/div>\n                                                    <div class=\"specs mb-2 d-flex align-items-center gap-2\">\n                                                    <img decoding=\"async\" alt=\"icon\"\n                                src=\"https:\/\/ga-p.com\/wp-content\/themes\/ga-p\/assets\/images\/mobile-primary.svg\" \/>\n                                                <a href=\"tel:(+34) 93 415 74 00\">(+34) 93 415 74 00<\/a>\n                    <\/div>\n                            <\/div>\n        <\/div>\n\n        <a href=\"https:\/\/ga-p.com\/pt-pt\/pessoa\/daniel-marin\/\" class=\"align-self-start align-self-lg-end\">\n            <div class=\"openCard\">\n                                    <img decoding=\"async\" alt=\"icon\" src=\"https:\/\/ga-p.com\/wp-content\/themes\/ga-p\/assets\/images\/arrow-open.svg\" \/>\n                    <img decoding=\"async\" alt=\"icon\" src=\"https:\/\/ga-p.com\/wp-content\/themes\/ga-p\/assets\/images\/arrow-open.svg\" \/>\n                \n            <\/div>\n        <\/a>\n    <\/div>\n                                <\/div>\n                                                                <div class=\"swiper-slide\">\n                                        <div\n        class=\"personaCard  egeo\">\n        <div class=\"personaContent\">\n                            <a href=\"https:\/\/ga-p.com\/pt-pt\/pessoa\/estibaliz-aranburu\/\">\n                    <div class=\"personaImage\"\n                        style=\"background:url(https:\/\/ga-p.com\/wp-content\/uploads\/2024\/05\/Fondo-personas-nueva-web.webp)\">\n                        <img decoding=\"async\" width=\"424\" height=\"424\" src=\"https:\/\/ga-p.com\/wp-content\/uploads\/2024\/06\/Estibaliz-Aranburu.png\" class=\"\" alt=\"Estibaliz Aranburu\" loading=\"eager\" srcset=\"https:\/\/ga-p.com\/wp-content\/uploads\/2024\/06\/Estibaliz-Aranburu.png 424w, https:\/\/ga-p.com\/wp-content\/uploads\/2024\/06\/Estibaliz-Aranburu-300x300.png 300w, https:\/\/ga-p.com\/wp-content\/uploads\/2024\/06\/Estibaliz-Aranburu-150x150.png 150w\" sizes=\"(max-width: 424px) 100vw, 424px\" \/>                    <\/div>\n                <\/a>\n                        <div class=\"personaInfo\">\n                <a style=\"text-decoration: none;\" href=\"https:\/\/ga-p.com\/pt-pt\/pessoa\/estibaliz-aranburu\/\">\n                    <div class=\"name\">Estibaliz Aranburu<\/div>\n                <\/a>\n                                    <div class=\"cargo\">S\u00f3cia<\/div>\n                                                    <div class=\"specs mb-2 d-flex align-items-center gap-2\">\n                                                    <img decoding=\"async\" class=\"image\" alt=\"email\"\n                                src=\"https:\/\/ga-p.com\/wp-content\/themes\/ga-p\/assets\/images\/email-icon.svg\" \/>\n                                                <a href=\"mailto:earanburu@ga-p.com\">earanburu@ga-p.com<\/a>\n                    <\/div>\n                                                    <div class=\"specs mb-2 d-flex align-items-center gap-2\">\n                                                    <img decoding=\"async\" class=\"image\" src=\"https:\/\/ga-p.com\/wp-content\/themes\/ga-p\/assets\/images\/profession-icon.svg\" \/>\n                                                <div class=\"areas\">\n                                                            <a\n                                    href=\"https:\/\/ga-p.com\/pt-pt\/area\/direito-comercial-societario\/\">Comercial, Societ\u00e1rio e M&amp;A, <\/a>\n                                                            <a\n                                    href=\"https:\/\/ga-p.com\/pt-pt\/area\/sustentabilidade\/\">Sustentabilidade<\/a>\n                                                    <\/div>\n                    <\/div>\n                                                    <div class=\"specs mb-2 d-flex align-items-center gap-2\">\n                                                    <img decoding=\"async\" class=\"image\" src=\"https:\/\/ga-p.com\/wp-content\/themes\/ga-p\/assets\/images\/select-oficinas.svg\" \/>\n                                                <a\n                            href=\"https:\/\/ga-p.com\/pt-pt\/escritorio\/bilbau\/\">Bilbau<\/a>\n                    <\/div>\n                                                    <div class=\"specs mb-2 d-flex align-items-center gap-2\">\n                                                    <img decoding=\"async\" alt=\"icon\"\n                                src=\"https:\/\/ga-p.com\/wp-content\/themes\/ga-p\/assets\/images\/mobile-primary.svg\" \/>\n                                                <a href=\"tel:(+34) 94 415 70 15\">(+34) 94 415 70 15<\/a>\n                    <\/div>\n                            <\/div>\n        <\/div>\n\n        <a href=\"https:\/\/ga-p.com\/pt-pt\/pessoa\/estibaliz-aranburu\/\" class=\"align-self-start align-self-lg-end\">\n            <div class=\"openCard\">\n                                    <img decoding=\"async\" alt=\"icon\" src=\"https:\/\/ga-p.com\/wp-content\/themes\/ga-p\/assets\/images\/arrow-open.svg\" \/>\n                    <img decoding=\"async\" alt=\"icon\" src=\"https:\/\/ga-p.com\/wp-content\/themes\/ga-p\/assets\/images\/arrow-open.svg\" \/>\n                \n            <\/div>\n        <\/a>\n    <\/div>\n                                <\/div>\n                                                                <div class=\"swiper-slide\">\n                                        <div\n        class=\"personaCard  egeo\">\n        <div class=\"personaContent\">\n                            <a href=\"https:\/\/ga-p.com\/pt-pt\/pessoa\/jesus-ibanez\/\">\n                    <div class=\"personaImage\"\n                        style=\"background:url(https:\/\/ga-p.com\/wp-content\/uploads\/2024\/05\/Fondo-personas-nueva-web.webp)\">\n                        <img decoding=\"async\" width=\"424\" height=\"424\" src=\"https:\/\/ga-p.com\/wp-content\/uploads\/2024\/06\/Jesus-Ibanez.png\" class=\"\" alt=\"Jes\u00fas Iba\u00f1ez\" loading=\"eager\" srcset=\"https:\/\/ga-p.com\/wp-content\/uploads\/2024\/06\/Jesus-Ibanez.png 424w, https:\/\/ga-p.com\/wp-content\/uploads\/2024\/06\/Jesus-Ibanez-300x300.png 300w, https:\/\/ga-p.com\/wp-content\/uploads\/2024\/06\/Jesus-Ibanez-150x150.png 150w\" sizes=\"(max-width: 424px) 100vw, 424px\" \/>                    <\/div>\n                <\/a>\n                        <div class=\"personaInfo\">\n                <a style=\"text-decoration: none;\" href=\"https:\/\/ga-p.com\/pt-pt\/pessoa\/jesus-ibanez\/\">\n                    <div class=\"name\">Jes\u00fas Iba\u00f1ez<\/div>\n                <\/a>\n                                    <div class=\"cargo\">S\u00f3cio<\/div>\n                                                    <div class=\"specs mb-2 d-flex align-items-center gap-2\">\n                                                    <img decoding=\"async\" class=\"image\" alt=\"email\"\n                                src=\"https:\/\/ga-p.com\/wp-content\/themes\/ga-p\/assets\/images\/email-icon.svg\" \/>\n                                                <a href=\"mailto:jibanez@ga-p.com\">jibanez@ga-p.com<\/a>\n                    <\/div>\n                                                    <div class=\"specs mb-2 d-flex align-items-center gap-2\">\n                                                    <img decoding=\"async\" class=\"image\" src=\"https:\/\/ga-p.com\/wp-content\/themes\/ga-p\/assets\/images\/profession-icon.svg\" \/>\n                                                <div class=\"areas\">\n                                                            <a\n                                    href=\"https:\/\/ga-p.com\/pt-pt\/area\/direito-comercial-societario\/\">Comercial, Societ\u00e1rio e M&amp;A<\/a>\n                                                    <\/div>\n                    <\/div>\n                                                    <div class=\"specs mb-2 d-flex align-items-center gap-2\">\n                                                    <img decoding=\"async\" class=\"image\" src=\"https:\/\/ga-p.com\/wp-content\/themes\/ga-p\/assets\/images\/select-oficinas.svg\" \/>\n                                                <a\n                            href=\"https:\/\/ga-p.com\/pt-pt\/escritorio\/valencia\/\">Val\u00eancia<\/a>\n                    <\/div>\n                                                    <div class=\"specs mb-2 d-flex align-items-center gap-2\">\n                                                    <img decoding=\"async\" alt=\"icon\"\n                                src=\"https:\/\/ga-p.com\/wp-content\/themes\/ga-p\/assets\/images\/mobile-primary.svg\" \/>\n                                                <a href=\"tel:(+34) 96 351 38 35\">(+34) 96 351 38 35<\/a>\n                    <\/div>\n                            <\/div>\n        <\/div>\n\n        <a href=\"https:\/\/ga-p.com\/pt-pt\/pessoa\/jesus-ibanez\/\" class=\"align-self-start align-self-lg-end\">\n            <div class=\"openCard\">\n                                    <img decoding=\"async\" alt=\"icon\" src=\"https:\/\/ga-p.com\/wp-content\/themes\/ga-p\/assets\/images\/arrow-open.svg\" \/>\n                    <img decoding=\"async\" alt=\"icon\" src=\"https:\/\/ga-p.com\/wp-content\/themes\/ga-p\/assets\/images\/arrow-open.svg\" \/>\n                \n            <\/div>\n        <\/a>\n    <\/div>\n                                <\/div>\n                                                                <div class=\"swiper-slide\">\n                                        <div\n        class=\"personaCard  egeo\">\n        <div class=\"personaContent\">\n                            <a href=\"https:\/\/ga-p.com\/pt-pt\/pessoa\/santiago-garrido-de-las-heras\/\">\n                    <div class=\"personaImage\"\n                        style=\"background:url(https:\/\/ga-p.com\/wp-content\/uploads\/2024\/05\/Fondo-personas-nueva-web.webp)\">\n                        <img decoding=\"async\" width=\"424\" height=\"424\" src=\"https:\/\/ga-p.com\/wp-content\/uploads\/2024\/06\/Santiago-Garrido.png\" class=\"\" alt=\"Santiago Garrido de las Heras\" loading=\"eager\" srcset=\"https:\/\/ga-p.com\/wp-content\/uploads\/2024\/06\/Santiago-Garrido.png 424w, https:\/\/ga-p.com\/wp-content\/uploads\/2024\/06\/Santiago-Garrido-300x300.png 300w, https:\/\/ga-p.com\/wp-content\/uploads\/2024\/06\/Santiago-Garrido-150x150.png 150w\" sizes=\"(max-width: 424px) 100vw, 424px\" \/>                    <\/div>\n                <\/a>\n                        <div class=\"personaInfo\">\n                <a style=\"text-decoration: none;\" href=\"https:\/\/ga-p.com\/pt-pt\/pessoa\/santiago-garrido-de-las-heras\/\">\n                    <div class=\"name\">Santiago Garrido de las Heras<\/div>\n                <\/a>\n                                    <div class=\"cargo\">S\u00f3cio<\/div>\n                                                    <div class=\"specs mb-2 d-flex align-items-center gap-2\">\n                                                    <img decoding=\"async\" class=\"image\" alt=\"email\"\n                                src=\"https:\/\/ga-p.com\/wp-content\/themes\/ga-p\/assets\/images\/email-icon.svg\" \/>\n                                                <a href=\"mailto:sgarrido@ga-p.com\">sgarrido@ga-p.com<\/a>\n                    <\/div>\n                                                    <div class=\"specs mb-2 d-flex align-items-center gap-2\">\n                                                    <img decoding=\"async\" class=\"image\" src=\"https:\/\/ga-p.com\/wp-content\/themes\/ga-p\/assets\/images\/profession-icon.svg\" \/>\n                                                <div class=\"areas\">\n                                                            <a\n                                    href=\"https:\/\/ga-p.com\/pt-pt\/area\/meio-ambiente\/\">Meio Ambiente, <\/a>\n                                                            <a\n                                    href=\"https:\/\/ga-p.com\/pt-pt\/area\/publico-e-sectores-regulados\/\">P\u00fablico e Setores Regulados, <\/a>\n                                                            <a\n                                    href=\"https:\/\/ga-p.com\/pt-pt\/area\/sustentabilidade\/\">Sustentabilidade<\/a>\n                                                    <\/div>\n                    <\/div>\n                                                    <div class=\"specs mb-2 d-flex align-items-center gap-2\">\n                                                    <img decoding=\"async\" class=\"image\" src=\"https:\/\/ga-p.com\/wp-content\/themes\/ga-p\/assets\/images\/select-oficinas.svg\" \/>\n                                                <a\n                            href=\"https:\/\/ga-p.com\/pt-pt\/escritorio\/madrid\/\">Madrid<\/a>\n                    <\/div>\n                                                    <div class=\"specs mb-2 d-flex align-items-center gap-2\">\n                                                    <img decoding=\"async\" alt=\"icon\"\n                                src=\"https:\/\/ga-p.com\/wp-content\/themes\/ga-p\/assets\/images\/mobile-primary.svg\" \/>\n                                                <a href=\"tel:(+34) 91 582 91 00\">(+34) 91 582 91 00<\/a>\n                    <\/div>\n                            <\/div>\n        <\/div>\n\n        <a href=\"https:\/\/ga-p.com\/pt-pt\/pessoa\/santiago-garrido-de-las-heras\/\" class=\"align-self-start align-self-lg-end\">\n            <div class=\"openCard\">\n                                    <img decoding=\"async\" alt=\"icon\" src=\"https:\/\/ga-p.com\/wp-content\/themes\/ga-p\/assets\/images\/arrow-open.svg\" \/>\n                    <img decoding=\"async\" alt=\"icon\" src=\"https:\/\/ga-p.com\/wp-content\/themes\/ga-p\/assets\/images\/arrow-open.svg\" \/>\n                \n            <\/div>\n        <\/a>\n    <\/div>\n                                <\/div>\n                                                                <div class=\"swiper-slide\">\n                                        <div\n        class=\"personaCard  egeo\">\n        <div class=\"personaContent\">\n                            <a href=\"https:\/\/ga-p.com\/pt-pt\/pessoa\/eduardo-gomez-de-la-cruz\/\">\n                    <div class=\"personaImage\"\n                        style=\"background:url(https:\/\/ga-p.com\/wp-content\/uploads\/2024\/05\/Fondo-personas-nueva-web.webp)\">\n                        <img decoding=\"async\" width=\"424\" height=\"424\" src=\"https:\/\/ga-p.com\/wp-content\/uploads\/2024\/06\/Eduardo-Gomez-de-la-Cruz.png\" class=\"\" alt=\"Eduardo G\u00f3mez de la Cruz\" loading=\"eager\" srcset=\"https:\/\/ga-p.com\/wp-content\/uploads\/2024\/06\/Eduardo-Gomez-de-la-Cruz.png 424w, https:\/\/ga-p.com\/wp-content\/uploads\/2024\/06\/Eduardo-Gomez-de-la-Cruz-300x300.png 300w, https:\/\/ga-p.com\/wp-content\/uploads\/2024\/06\/Eduardo-Gomez-de-la-Cruz-150x150.png 150w\" sizes=\"(max-width: 424px) 100vw, 424px\" \/>                    <\/div>\n                <\/a>\n                        <div class=\"personaInfo\">\n                <a style=\"text-decoration: none;\" href=\"https:\/\/ga-p.com\/pt-pt\/pessoa\/eduardo-gomez-de-la-cruz\/\">\n                    <div class=\"name\">Eduardo G\u00f3mez de la Cruz<\/div>\n                <\/a>\n                                    <div class=\"cargo\">Counsel<\/div>\n                                                    <div class=\"specs mb-2 d-flex align-items-center gap-2\">\n                                                    <img decoding=\"async\" class=\"image\" alt=\"email\"\n                                src=\"https:\/\/ga-p.com\/wp-content\/themes\/ga-p\/assets\/images\/email-icon.svg\" \/>\n                                                <a href=\"mailto:e.gomez@ga-p.com\">e.gomez@ga-p.com<\/a>\n                    <\/div>\n                                                    <div class=\"specs mb-2 d-flex align-items-center gap-2\">\n                                                    <img decoding=\"async\" class=\"image\" src=\"https:\/\/ga-p.com\/wp-content\/themes\/ga-p\/assets\/images\/profession-icon.svg\" \/>\n                                                <div class=\"areas\">\n                                                            <a\n                                    href=\"https:\/\/ga-p.com\/pt-pt\/area\/concorrencia-e-direito-da-uniao-europeia\/\">Concorr\u00eancia e Direito da Uni\u00e3o Europeia<\/a>\n                                                    <\/div>\n                    <\/div>\n                                                    <div class=\"specs mb-2 d-flex align-items-center gap-2\">\n                                                    <img decoding=\"async\" class=\"image\" src=\"https:\/\/ga-p.com\/wp-content\/themes\/ga-p\/assets\/images\/select-oficinas.svg\" \/>\n                                                <a\n                            href=\"https:\/\/ga-p.com\/pt-pt\/escritorio\/madrid\/\">Madrid<\/a>\n                    <\/div>\n                                                    <div class=\"specs mb-2 d-flex align-items-center gap-2\">\n                                                    <img decoding=\"async\" alt=\"icon\"\n                                src=\"https:\/\/ga-p.com\/wp-content\/themes\/ga-p\/assets\/images\/mobile-primary.svg\" \/>\n                                                <a href=\"tel:(+34) 91 582 91 00\">(+34) 91 582 91 00<\/a>\n                    <\/div>\n                            <\/div>\n        <\/div>\n\n        <a href=\"https:\/\/ga-p.com\/pt-pt\/pessoa\/eduardo-gomez-de-la-cruz\/\" class=\"align-self-start align-self-lg-end\">\n            <div class=\"openCard\">\n                                    <img decoding=\"async\" alt=\"icon\" src=\"https:\/\/ga-p.com\/wp-content\/themes\/ga-p\/assets\/images\/arrow-open.svg\" \/>\n                    <img decoding=\"async\" alt=\"icon\" src=\"https:\/\/ga-p.com\/wp-content\/themes\/ga-p\/assets\/images\/arrow-open.svg\" \/>\n                \n            <\/div>\n        <\/a>\n    <\/div>\n                                <\/div>\n                                                                <div class=\"swiper-slide\">\n                                        <div\n        class=\"personaCard  noDetail egeo\">\n        <div class=\"personaContent\">\n                            <div class=\"personaImage expandCardTrigger\"\n                    style=\"background:url(https:\/\/ga-p.com\/wp-content\/uploads\/2024\/05\/Fondo-personas-nueva-web.webp)\">\n                    <img decoding=\"async\" width=\"424\" height=\"424\" src=\"https:\/\/ga-p.com\/wp-content\/uploads\/2024\/06\/Angel-Garcia-2.png\" class=\"\" alt=\"\u00c1ngel Garc\u00eda Vidal\" loading=\"eager\" srcset=\"https:\/\/ga-p.com\/wp-content\/uploads\/2024\/06\/Angel-Garcia-2.png 424w, https:\/\/ga-p.com\/wp-content\/uploads\/2024\/06\/Angel-Garcia-2-300x300.png 300w, https:\/\/ga-p.com\/wp-content\/uploads\/2024\/06\/Angel-Garcia-2-150x150.png 150w\" sizes=\"(max-width: 424px) 100vw, 424px\" \/>                <\/div>\n                        <div class=\"personaInfo\">\n                <div class=\"name expandCardTrigger\">\u00c1ngel Garc\u00eda Vidal<\/div>\n                                    <div class=\"cargo\">Conselho acad\u00e9mico<\/div>\n                                <div class=\"specsCont\">\n                                            <div class=\"specs mb-2 d-flex align-items-center gap-2\">\n                                                            <img decoding=\"async\" class=\"image\" alt=\"email\"\n                                    src=\"https:\/\/ga-p.com\/wp-content\/themes\/ga-p\/assets\/images\/email-icon.svg\" \/>\n                                                        <a href=\"mailto:agarciav@ga-p.com\">agarciav@ga-p.com<\/a>\n                        <\/div>\n                                                                <div class=\"specs mb-2 d-flex align-items-center gap-2\">\n                                                            <img decoding=\"async\" class=\"image\"\n                                    src=\"https:\/\/ga-p.com\/wp-content\/themes\/ga-p\/assets\/images\/select-oficinas.svg\" \/>\n                                                        <a href=\"tel:(+34) 91 582 91 00\">Madrid<\/a>\n                        <\/div>\n                                    <\/div>\n            <\/div>\n            <div class=\"personaExtraInfo\" style=\"display: none\">\n                <div class=\"sectoresAreas w-100\">\n                                            <div class=\"areas\">\n                                                            <a\n                                    href=\"https:\/\/ga-p.com\/pt-pt\/area\/direito-comercial-societario\/\">Comercial, Societ\u00e1rio e M&amp;A, <\/a>\n                                                            <a\n                                    href=\"https:\/\/ga-p.com\/pt-pt\/area\/propiedad-industrial-intelectual\/\">Propriedade Industrial e Intelectual<\/a>\n                                                    <\/div>\n                                    <\/div>\n            <\/div>\n        <\/div>\n                                    <img decoding=\"async\" class=\"expandCard align-self-start align-self-lg-end\" alt=\"icon\"\n                    src=\"https:\/\/ga-p.com\/wp-content\/themes\/ga-p\/assets\/images\/expand-card.svg\" \/>\n                <img decoding=\"async\" class=\"collapseCard align-self-start align-self-lg-end\" alt=\"icon\"\n                    src=\"https:\/\/ga-p.com\/wp-content\/themes\/ga-p\/assets\/images\/collapse-card.svg\" \/>\n                        <\/div>\n\n                                <\/div>\n                                                                <div class=\"swiper-slide\">\n                                        <div\n        class=\"personaCard  egeo\">\n        <div class=\"personaContent\">\n                            <a href=\"https:\/\/ga-p.com\/pt-pt\/pessoa\/nuria-ribera\/\">\n                    <div class=\"personaImage\"\n                        style=\"background:url(https:\/\/ga-p.com\/wp-content\/uploads\/2024\/05\/Fondo-personas-nueva-web.webp)\">\n                        <img decoding=\"async\" width=\"424\" height=\"424\" src=\"https:\/\/ga-p.com\/wp-content\/uploads\/2024\/06\/Nuria-Ribera.png\" class=\"\" alt=\"N\u00faria Ribera\" loading=\"eager\" srcset=\"https:\/\/ga-p.com\/wp-content\/uploads\/2024\/06\/Nuria-Ribera.png 424w, https:\/\/ga-p.com\/wp-content\/uploads\/2024\/06\/Nuria-Ribera-300x300.png 300w, https:\/\/ga-p.com\/wp-content\/uploads\/2024\/06\/Nuria-Ribera-150x150.png 150w\" sizes=\"(max-width: 424px) 100vw, 424px\" \/>                    <\/div>\n                <\/a>\n                        <div class=\"personaInfo\">\n                <a style=\"text-decoration: none;\" href=\"https:\/\/ga-p.com\/pt-pt\/pessoa\/nuria-ribera\/\">\n                    <div class=\"name\">N\u00faria Ribera<\/div>\n                <\/a>\n                                    <div class=\"cargo\">Associada s\u00e9nior<\/div>\n                                                    <div class=\"specs mb-2 d-flex align-items-center gap-2\">\n                                                    <img decoding=\"async\" class=\"image\" alt=\"email\"\n                                src=\"https:\/\/ga-p.com\/wp-content\/themes\/ga-p\/assets\/images\/email-icon.svg\" \/>\n                                                <a href=\"mailto:nribera@ga-p.com\">nribera@ga-p.com<\/a>\n                    <\/div>\n                                                    <div class=\"specs mb-2 d-flex align-items-center gap-2\">\n                                                    <img decoding=\"async\" class=\"image\" src=\"https:\/\/ga-p.com\/wp-content\/themes\/ga-p\/assets\/images\/profession-icon.svg\" \/>\n                                                <div class=\"areas\">\n                                                            <a\n                                    href=\"https:\/\/ga-p.com\/pt-pt\/area\/propiedad-industrial-intelectual\/\">Propriedade Industrial e Intelectual<\/a>\n                                                    <\/div>\n                    <\/div>\n                                                    <div class=\"specs mb-2 d-flex align-items-center gap-2\">\n                                                    <img decoding=\"async\" class=\"image\" src=\"https:\/\/ga-p.com\/wp-content\/themes\/ga-p\/assets\/images\/select-oficinas.svg\" \/>\n                                                <a\n                            href=\"https:\/\/ga-p.com\/pt-pt\/escritorio\/barcelona\/\">Barcelona<\/a>\n                    <\/div>\n                                                    <div class=\"specs mb-2 d-flex align-items-center gap-2\">\n                                                    <img decoding=\"async\" alt=\"icon\"\n                                src=\"https:\/\/ga-p.com\/wp-content\/themes\/ga-p\/assets\/images\/mobile-primary.svg\" \/>\n                                                <a href=\"tel:(+34) 93 415 74 00\">(+34) 93 415 74 00<\/a>\n                    <\/div>\n                            <\/div>\n        <\/div>\n\n        <a href=\"https:\/\/ga-p.com\/pt-pt\/pessoa\/nuria-ribera\/\" class=\"align-self-start align-self-lg-end\">\n            <div class=\"openCard\">\n                                    <img decoding=\"async\" alt=\"icon\" src=\"https:\/\/ga-p.com\/wp-content\/themes\/ga-p\/assets\/images\/arrow-open.svg\" \/>\n                    <img decoding=\"async\" alt=\"icon\" src=\"https:\/\/ga-p.com\/wp-content\/themes\/ga-p\/assets\/images\/arrow-open.svg\" \/>\n                \n            <\/div>\n        <\/a>\n    <\/div>\n                                <\/div>\n                                                            <\/div>\n                            <div class=\"swiperPagination mt-3\">\n                                <div class=\"container\">\n                                    <div class=\"row\">\n                                        <div class=\"col-6\">\n                                            <div class=\"swiperBullets\"><\/div>\n                                        <\/div>\n                                        <div class=\"col-6 swiperArrowsMobile\">\n                                            <div class=\"swiperCargosArrows swiperArrows\">\n                                                <div class=\"d-flex align-items-center gap-4 justify-content-end\">\n                                                    <div class=\"swiper-button-prev\"><img decoding=\"async\" alt=\"icon\" src=\"https:\/\/ga-p.com\/wp-content\/themes\/ga-p\/assets\/images\/slider-arrow.svg\" \/><\/div>\n                                                    <div class=\"swiper-button-next\"><img decoding=\"async\" alt=\"icon\" src=\"https:\/\/ga-p.com\/wp-content\/themes\/ga-p\/assets\/images\/slider-arrow.svg\" \/><\/div>\n                                                <\/div>\n                                            <\/div>\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div>\n                        <\/div>\n                    <\/div>\n                <\/div>\n            <script>\n                jQuery(document).ready(function ($){\n                    var swiperPersGrupo_0 = new Swiper(\".CargosPersonas .swiperCargos.swiperGrupo-0\", {\n                        slidesPerView: 1,\n                        spaceBetween: 24,\n                        navigation: {\n                            nextEl: \".CargosPersonas .swiperGrupo-0 .swiperArrows .swiper-button-next\",\n                            prevEl: \".CargosPersonas .swiperGrupo-0 .swiperArrows .swiper-button-prev\",\n                        },\n                        pagination: {\n                            el: '.CargosPersonas .swiperGrupo-0 .swiperBullets',\n                            clickable: true,\n                            type: $.fn.isMobileViewport() ? 'fraction' : 'bullets',\n                            formatFractionCurrent: function (number) { return ('0' + number).slice(-2); },\n                            formatFractionTotal: function (number) { return ('0' + number).slice(-2); },\n                            renderFraction: function (currentClass, totalClass) {\n                                return '<span class=\"swiper-pagination-fraction ' + currentClass + '\"><\/span>' +\n                                    ' \/ ' +\n                                    '<span class=\"swiper-pagination-fraction ' + totalClass + '\"><\/span>';\n                            }\n                        },\n                    });\n                })\n            <\/script>\n                    <\/div>\n    <\/div>\n<\/div>\n\n\n\n\n<div id=\"CarruselReconocimientos-block_d74eb78a8131eff53551ca8379d44082\" class=\"v2 CarruselReconocimientos coral\">\n    <div class=\"backgroundText\">\n        <div class=\"texto_de_fondo\">\n                    <\/div>\n    <\/div>\n    <div class=\"container\">\n        <div class=\"row textContent\">\n            <div class=\"col-12 col-lg-6\">\n                <div class=\"title\"><h2 class='titulo'>Reconhecimentos<\/h2>\n<\/div>\n            <\/div>\n            <div class=\"col-12 col-lg-6\">\n                <div class=\"textDescription\"><p class='texto'>Somos reconhecidos a n\u00edvel nacional e internacional pelos nossos servi\u00e7os jur\u00eddicos, gest\u00e3o, servi\u00e7o ao cliente, inova\u00e7\u00e3o e excel\u00eancia t\u00e9cnica.<\/p>\n<\/div>\n                            <\/div>\n        <\/div>\n        <div class=\"row\">\n            <div class=\"col-12  blockFilter\">\n                <div id=\"selector_fechas\"><\/div>\n                <div class=\"swiperRecArrows swiperArrows active d-none d-lg-block \" data-arrows=\"#nav-reconocimientos\">\n                    <div class=\"d-flex align-items-center gap-4 justify-content-end\">\n                        <div class=\"swiper-button-prev\"><img decoding=\"async\" alt=\"icon\" src=\"https:\/\/ga-p.com\/wp-content\/themes\/ga-p\/assets\/images\/slider-arrow.svg\" \/><\/div>\n                        <div class=\"swiper-button-next\"><img decoding=\"async\" alt=\"icon\" src=\"https:\/\/ga-p.com\/wp-content\/themes\/ga-p\/assets\/images\/slider-arrow.svg\" \/><\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n\n            <div class=\"swiper mySwiper swiperRec\">\n            <div class=\"swiper-wrapper\">\n                                    <div class=\"swiper-slide y2025\">\n                        <div class=\"reconocimento \">\n    <div class=\"rewardBlock\">\n        <div>\n                            <img decoding=\"async\" width=\"300\" height=\"252\" src=\"https:\/\/ga-p.com\/wp-content\/uploads\/2025\/03\/Firm-Logo-Europe-2025-300x252.jpg\" class=\"imagen\" alt=\"Chambers &amp; Partners Europe, 2025. Life Sciences\" loading=\"lazy\" srcset=\"https:\/\/ga-p.com\/wp-content\/uploads\/2025\/03\/Firm-Logo-Europe-2025-300x252.jpg 300w, https:\/\/ga-p.com\/wp-content\/uploads\/2025\/03\/Firm-Logo-Europe-2025-1024x860.jpg 1024w, https:\/\/ga-p.com\/wp-content\/uploads\/2025\/03\/Firm-Logo-Europe-2025-768x645.jpg 768w, https:\/\/ga-p.com\/wp-content\/uploads\/2025\/03\/Firm-Logo-Europe-2025.jpg 1072w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>                    <\/div>\n\n\n        \n        <div class=\"info\">\n            <div class=\"titulo\">\n                Chambers &#038; Partners Europe, 2025. Life Sciences            <\/div>\n            <div class=\"excerpt\">\n                &#8220;The law firm offers commitment, availability and clarity in its explanations and arguments.&#8221;            <\/div>\n            \n        <\/div>\n                        <\/div>\n    <\/div>                    <\/div>\n                                    <div class=\"swiper-slide y2025\">\n                        <div class=\"reconocimento \">\n    <div class=\"rewardBlock\">\n        <div>\n                            <img decoding=\"async\" width=\"300\" height=\"252\" src=\"https:\/\/ga-p.com\/wp-content\/uploads\/2025\/03\/Firm-Logo-Europe-2025-300x252.jpg\" class=\"imagen\" alt=\"Chambers &amp; Partners Europe, 2025. Life Sciences\" loading=\"lazy\" srcset=\"https:\/\/ga-p.com\/wp-content\/uploads\/2025\/03\/Firm-Logo-Europe-2025-300x252.jpg 300w, https:\/\/ga-p.com\/wp-content\/uploads\/2025\/03\/Firm-Logo-Europe-2025-1024x860.jpg 1024w, https:\/\/ga-p.com\/wp-content\/uploads\/2025\/03\/Firm-Logo-Europe-2025-768x645.jpg 768w, https:\/\/ga-p.com\/wp-content\/uploads\/2025\/03\/Firm-Logo-Europe-2025.jpg 1072w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>                    <\/div>\n\n\n        \n        <div class=\"info\">\n            <div class=\"titulo\">\n                Chambers &#038; Partners Europe, 2025. Life Sciences            <\/div>\n            <div class=\"excerpt\">\n                &#8220;G\u00f3mez-Acebo &#038; Pombo offers a very good service with an excellent response time.&#8221;            <\/div>\n            \n        <\/div>\n                        <\/div>\n    <\/div>                    <\/div>\n                                    <div class=\"swiper-slide y2025\">\n                        <div class=\"reconocimento \">\n    <div class=\"rewardBlock\">\n        <div>\n                            <img decoding=\"async\" width=\"300\" height=\"252\" src=\"https:\/\/ga-p.com\/wp-content\/uploads\/2025\/03\/Firm-Logo-Europe-2025-300x252.jpg\" class=\"imagen\" alt=\"Chambers &amp; Partners Europe, 2025. Life Sciences\" loading=\"lazy\" srcset=\"https:\/\/ga-p.com\/wp-content\/uploads\/2025\/03\/Firm-Logo-Europe-2025-300x252.jpg 300w, https:\/\/ga-p.com\/wp-content\/uploads\/2025\/03\/Firm-Logo-Europe-2025-1024x860.jpg 1024w, https:\/\/ga-p.com\/wp-content\/uploads\/2025\/03\/Firm-Logo-Europe-2025-768x645.jpg 768w, https:\/\/ga-p.com\/wp-content\/uploads\/2025\/03\/Firm-Logo-Europe-2025.jpg 1072w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>                    <\/div>\n\n\n        \n        <div class=\"info\">\n            <div class=\"titulo\">\n                Chambers &#038; Partners Europe, 2025. Life Sciences            <\/div>\n            <div class=\"excerpt\">\n                &#8220;G\u00f3mez-Acebo&#8217;s team has a great understanding of business and is oriented towards achieving results.&#8221;            <\/div>\n            \n        <\/div>\n                        <\/div>\n    <\/div>                    <\/div>\n                                    <div class=\"swiper-slide y2025\">\n                        <div class=\"reconocimento \">\n    <div class=\"rewardBlock\">\n        <div>\n                            <img decoding=\"async\" width=\"300\" height=\"252\" src=\"https:\/\/ga-p.com\/wp-content\/uploads\/2025\/03\/Firm-Logo-Europe-2025-300x252.jpg\" class=\"imagen\" alt=\"Chambers &amp; Partners Europe, 2025. Life Sciences\" loading=\"lazy\" srcset=\"https:\/\/ga-p.com\/wp-content\/uploads\/2025\/03\/Firm-Logo-Europe-2025-300x252.jpg 300w, https:\/\/ga-p.com\/wp-content\/uploads\/2025\/03\/Firm-Logo-Europe-2025-1024x860.jpg 1024w, https:\/\/ga-p.com\/wp-content\/uploads\/2025\/03\/Firm-Logo-Europe-2025-768x645.jpg 768w, https:\/\/ga-p.com\/wp-content\/uploads\/2025\/03\/Firm-Logo-Europe-2025.jpg 1072w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>                    <\/div>\n\n\n        \n        <div class=\"info\">\n            <div class=\"titulo\">\n                Chambers &#038; Partners Europe, 2025. Life Sciences            <\/div>\n            <div class=\"excerpt\">\n                &#8220;They have large, highly qualified multidisciplinary team that is very prepared and very coordinated.&#8221;            <\/div>\n            \n        <\/div>\n                        <\/div>\n    <\/div>                    <\/div>\n                                    <div class=\"swiper-slide y2024\">\n                        <div class=\"reconocimento \">\n    <div class=\"rewardBlock\">\n        <div>\n                            <img decoding=\"async\" width=\"250\" height=\"270\" src=\"https:\/\/ga-p.com\/wp-content\/uploads\/2018\/03\/reconocimiento_the_legal_500_60-e1533553443883.jpg\" class=\"imagen\" alt=\"Legal 500 2024. Industry Focus: Healthcare and Life Sciences\" loading=\"lazy\" \/>                    <\/div>\n\n\n        \n        <div class=\"info\">\n            <div class=\"titulo\">\n                Legal 500 2024. Industry Focus: Healthcare and Life Sciences            <\/div>\n            <div class=\"excerpt\">\n                \u2018They have expert lawyers in all areas in the same office, respond promptly and in a very practical manner. I especially thank Irene Fern\u00e1ndez Puyol, who has always served us very well.\u2019            <\/div>\n            \n        <\/div>\n                        <\/div>\n    <\/div>                    <\/div>\n                                    <div class=\"swiper-slide y2024\">\n                        <div class=\"reconocimento \">\n    <div class=\"rewardBlock\">\n        <div>\n                            <img decoding=\"async\" width=\"250\" height=\"270\" src=\"https:\/\/ga-p.com\/wp-content\/uploads\/2018\/03\/reconocimiento_the_legal_500_60-e1533553443883.jpg\" class=\"imagen\" alt=\"Legal 500 2024. Industry Focus: Healthcare and Life Sciences \u2013 Spain\" loading=\"lazy\" \/>                    <\/div>\n\n\n        \n        <div class=\"info\">\n            <div class=\"titulo\">\n                Legal 500 2024. Industry Focus: Healthcare and Life Sciences \u2013 Spain            <\/div>\n            <div class=\"excerpt\">\n                The firm is multidisciplinary; there are experts in all sectors and practice areas that one needs. Serves clients very quickly, practically and politely. They also provide you with newsletters and workshops with news from the legal world.\u2019            <\/div>\n            \n        <\/div>\n                        <\/div>\n    <\/div>                    <\/div>\n                                    <div class=\"swiper-slide y2024\">\n                        <div class=\"reconocimento \">\n    <div class=\"rewardBlock\">\n        <div>\n                            <img decoding=\"async\" width=\"300\" height=\"252\" src=\"https:\/\/ga-p.com\/wp-content\/uploads\/2024\/03\/Firm-Logo-300x252.jpg\" class=\"imagen\" alt=\"Chambers &amp; Partners, Europe 2024 \u2013 Life Sciences\" loading=\"lazy\" srcset=\"https:\/\/ga-p.com\/wp-content\/uploads\/2024\/03\/Firm-Logo-300x252.jpg 300w, https:\/\/ga-p.com\/wp-content\/uploads\/2024\/03\/Firm-Logo-1024x860.jpg 1024w, https:\/\/ga-p.com\/wp-content\/uploads\/2024\/03\/Firm-Logo-768x645.jpg 768w, https:\/\/ga-p.com\/wp-content\/uploads\/2024\/03\/Firm-Logo.jpg 1072w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>                    <\/div>\n\n\n        \n        <div class=\"info\">\n            <div class=\"titulo\">\n                Chambers &#038; Partners, Europe 2024 \u2013 Life Sciences            <\/div>\n            <div class=\"excerpt\">\n                &#8211; &#8220;The team is composed of senior lawyers that can evaluate with depth a great variety of legal topics in a practical way.&#8221;            <\/div>\n            \n        <\/div>\n                        <\/div>\n    <\/div>                    <\/div>\n                            <\/div>\n        <\/div>\n        <div class=\"container\">\n            <div class=\"row mt-3 mt-lg-0\">\n                <div class=\"col-6 col-lg-12\">\n                    <div class=\"swiperBullets swiperRecPagination\"><\/div>\n                <\/div>\n                <div class=\"d-block d-lg-none col-6\">\n                    <div class=\"swiperRecArrows swiperArrows\">\n                        <div class=\"d-flex align-items-center gap-4 justify-content-end\">\n                            <div class=\"swiper-button-prev\"><img decoding=\"async\" alt=\"icon\" src=\"https:\/\/ga-p.com\/wp-content\/themes\/ga-p\/assets\/images\/slider-arrow.svg\" \/><\/div>\n                            <div class=\"swiper-button-next\"><img decoding=\"async\" alt=\"icon\" src=\"https:\/\/ga-p.com\/wp-content\/themes\/ga-p\/assets\/images\/slider-arrow.svg\" \/><\/div>\n                        <\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n<script>\n    const opciones_carrusel_reconocimientos_array  = [\n                {label: '2025', value: 'y2025'},\n                {label: '2024', value: 'y2024'},\n            ]\n<\/script>\n\n\n\n\n<div id=\"NoticiasPublicacionesRecomendadas-block_d2696627d657394712d8db30e8e609ff\" class=\" v2 NoticiasPublicacionesRecomendadas\" style=\"background-color: #ffffff\">\n\n    <div class=\"container\">\n        <div class=\"row align-items-end flex-column flex-lg-row titleRow\">\n            <div class=\"col-12 col-lg-10\">\n                <div class=\"title\"><h2 class=''>Not\u00edcias<\/h2>\n<\/div>\n            <\/div>\n            <div class=\"col-12 col-lg-2\">\n                                    <div id=\"relacionadas_selector_fechas\"><\/div>\n                            <\/div>\n        <\/div>\n       <div class=\"row align-items-end\">\n           <div class=\"col-12 col-lg-11\">\n               <div class=\"selectores\">\n                   <div class=\"nav nav-tabs\" id=\"nav-tab\" role=\"tablist\">\n                                                  <button class=\"nav-link y2025 y2024  active\" id=\"nav-noticias-tab\" data-bs-toggle=\"tab\" data-bs-target=\"#nav-noticias\" type=\"button\" role=\"tab\" aria-controls=\"nav-noticias\" aria-selected=\"true\">Not\u00edcias<\/button>\n                                                                         <button class=\"nav-link y2018  \" id=\"nav-publicaciones-tab\" data-bs-toggle=\"tab\" data-bs-target=\"#nav-publicaciones\" type=\"button\" role=\"tab\" aria-controls=\"nav-publicaciones\" aria-selected=\"false\">Publica\u00e7\u00f5es<\/button>\n                                          <\/div>\n               <\/div>\n           <\/div>\n           <div class=\"d-none d-lg-block col-1\">\n               <div class=\"swiperNotArrows swiperArrows active\" data-arrows=\"#nav-noticias\">\n                   <div class=\"d-flex align-items-center gap-4 justify-content-end\">\n                       <div class=\"swiper-button-prev\"><img decoding=\"async\" alt=\"icon\" src=\"https:\/\/ga-p.com\/wp-content\/themes\/ga-p\/assets\/images\/slider-arrow.svg\" \/><\/div>\n                       <div class=\"swiper-button-next\"><img decoding=\"async\" alt=\"icon\" src=\"https:\/\/ga-p.com\/wp-content\/themes\/ga-p\/assets\/images\/slider-arrow.svg\" \/><\/div>\n                   <\/div>\n               <\/div>\n               <div class=\"swiperPubArrows swiperArrows\" data-arrows=\"#nav-publicaciones\">\n                   <div class=\"d-flex align-items-center gap-4 justify-content-end\">\n                       <div class=\"swiper-button-prev\"><img decoding=\"async\" alt=\"icon\" src=\"https:\/\/ga-p.com\/wp-content\/themes\/ga-p\/assets\/images\/slider-arrow.svg\" \/><\/div>\n                       <div class=\"swiper-button-next\"><img decoding=\"async\" alt=\"icon\" src=\"https:\/\/ga-p.com\/wp-content\/themes\/ga-p\/assets\/images\/slider-arrow.svg\" \/><\/div>\n                   <\/div>\n               <\/div>\n           <\/div>\n       <\/div>\n    <\/div>\n    <div class=\"tab-content\" id=\"nav-tabContent\">\n                    <div class=\"tab-pane fade show active\" id=\"nav-noticias\" role=\"tabpanel\" aria-labelledby=\"nav-noticias-tab\" tabindex=\"0\">\n                <div class=\"swiper mySwiper swiperNot\">\n                    <div class=\"swiper-wrapper\">\n                                                    <div class=\"swiper-slide y2025\">\n                                <a style=\"text-decoration: none\" href=\"https:\/\/ga-p.com\/pt-pt\/noticia\/ga_p-assessora-a-hawk-infinity-na-aquisicao-da-fba-indaga-soft\/\">\n    <div class=\"noticiaCard\">\n        <div class=\"content\">\n            <div class=\"tag\">NOT\u00cdCIAS<\/div>\n            <div class=\"titulo\">\n                GA_P assessora Hawk Infinity na aquisi\u00e7\u00e3o da FBA Indaga Soft            <\/div>\n            <div class=\"excerpt\">\n                            <\/div>\n            <div class=\"fecha d-flex align-items-center gap-2\">\n                <img decoding=\"async\" alt=\"icon\" src=\"https:\/\/ga-p.com\/wp-content\/themes\/ga-p\/assets\/images\/clock-icon.svg\" \/>\n                10 Jul, 2025            <\/div>\n\n\n                            <div class=\"author d-flex align-items-center gap-2\">\n                    <img decoding=\"async\" alt=\"icon\" src=\"https:\/\/ga-p.com\/wp-content\/themes\/ga-p\/assets\/images\/author-icon.svg\" \/><span>\n                    M\u00f3nica Weimann, Cristina S\u00e1nchez Weickgenannt, Mari\u0301a Garci\u0301a de la Concha                <\/span><\/div>\n            \n        <\/div>\n        <div class=\"openCard me-0 ms-auto\">\n            <img decoding=\"async\" alt=\"icon\" src=\"https:\/\/ga-p.com\/wp-content\/themes\/ga-p\/assets\/images\/arrow-open.svg\" \/>\n            <img decoding=\"async\" alt=\"icon\" src=\"https:\/\/ga-p.com\/wp-content\/themes\/ga-p\/assets\/images\/arrow-open.svg\" \/>\n        <\/div>\n    <\/div>\n<\/a>\n                            <\/div>\n                                                    <div class=\"swiper-slide y2025\">\n                                <a style=\"text-decoration: none\" href=\"https:\/\/ga-p.com\/pt-pt\/noticia\/ga_p-asesora-a-pai-partners-en-la-compra-de-nuzoa-a-abac-capital\/\">\n    <div class=\"noticiaCard\">\n        <div class=\"content\">\n            <div class=\"tag\">NOT\u00cdCIAS<\/div>\n            <div class=\"titulo\">\n                GA_P assessora PAI Partners na aquisi\u00e7\u00e3o de Nuzoa a Abac Capital            <\/div>\n            <div class=\"excerpt\">\n                G\u00f3mez-Acebo &#038; Pombo assessorou PAI PARTNERS, fundo de private equity, na aquisi\u00e7\u00e3o do Grupo Nuzoa, l\u00edder na distribui\u00e7\u00e3o de produtos e servi\u00e7os de sa\u00fade animal na Pen\u00ednsula Ib\u00e9rica, \u00e0 Abac Capital.            <\/div>\n            <div class=\"fecha d-flex align-items-center gap-2\">\n                <img decoding=\"async\" alt=\"icon\" src=\"https:\/\/ga-p.com\/wp-content\/themes\/ga-p\/assets\/images\/clock-icon.svg\" \/>\n                24 Mar, 2025            <\/div>\n\n\n                            <div class=\"author d-flex align-items-center gap-2\">\n                    <img decoding=\"async\" alt=\"icon\" src=\"https:\/\/ga-p.com\/wp-content\/themes\/ga-p\/assets\/images\/author-icon.svg\" \/><span>\n                    Pablo Fern\u00e1ndez Cortijo, Andr\u00e9s Castro, Jos\u00e9 Luis Rodr\u00edguez                <\/span><\/div>\n            \n        <\/div>\n        <div class=\"openCard me-0 ms-auto\">\n            <img decoding=\"async\" alt=\"icon\" src=\"https:\/\/ga-p.com\/wp-content\/themes\/ga-p\/assets\/images\/arrow-open.svg\" \/>\n            <img decoding=\"async\" alt=\"icon\" src=\"https:\/\/ga-p.com\/wp-content\/themes\/ga-p\/assets\/images\/arrow-open.svg\" \/>\n        <\/div>\n    <\/div>\n<\/a>\n                            <\/div>\n                                                    <div class=\"swiper-slide y2025\">\n                                <a style=\"text-decoration: none\" href=\"https:\/\/ga-p.com\/pt-pt\/noticia\/ga_p-asesora-en-la-emision-de-bonos-de-grifols-por-valor-de-e1-300m\/\">\n    <div class=\"noticiaCard\">\n        <div class=\"content\">\n            <div class=\"tag\">NOT\u00cdCIAS<\/div>\n            <div class=\"titulo\">\n                GA_P presta assessoria na emiss\u00e3o de obriga\u00e7\u00f5es da Grifols no valor de \u20ac1.300m            <\/div>\n            <div class=\"excerpt\">\n                G\u00f3mez-Acebo &#038; Pombo assessorou os subscritores das obriga\u00e7\u00f5es de 1.300 milh\u00f5es de euros emitidas pela Grifols, com vencimento em maio de 2030.            <\/div>\n            <div class=\"fecha d-flex align-items-center gap-2\">\n                <img decoding=\"async\" alt=\"icon\" src=\"https:\/\/ga-p.com\/wp-content\/themes\/ga-p\/assets\/images\/clock-icon.svg\" \/>\n                29 Jan, 2025            <\/div>\n\n\n                            <div class=\"author d-flex align-items-center gap-2\">\n                    <img decoding=\"async\" alt=\"icon\" src=\"https:\/\/ga-p.com\/wp-content\/themes\/ga-p\/assets\/images\/author-icon.svg\" \/><span>\n                    \u00c1lvaro Sainz                <\/span><\/div>\n            \n        <\/div>\n        <div class=\"openCard me-0 ms-auto\">\n            <img decoding=\"async\" alt=\"icon\" src=\"https:\/\/ga-p.com\/wp-content\/themes\/ga-p\/assets\/images\/arrow-open.svg\" \/>\n            <img decoding=\"async\" alt=\"icon\" src=\"https:\/\/ga-p.com\/wp-content\/themes\/ga-p\/assets\/images\/arrow-open.svg\" \/>\n        <\/div>\n    <\/div>\n<\/a>\n                            <\/div>\n                                                    <div class=\"swiper-slide y2024\">\n                                <a style=\"text-decoration: none\" href=\"https:\/\/ga-p.com\/pt-pt\/noticia\/ga_p-assessora-ampersand-capital-partners-num-investimento-na-vivebiotech\/\">\n    <div class=\"noticiaCard\">\n        <div class=\"content\">\n            <div class=\"tag\">NOT\u00cdCIAS<\/div>\n            <div class=\"titulo\">\n                GA_P assessora Ampersand Capital Partners num investimento na Vivebiotech            <\/div>\n            <div class=\"excerpt\">\n                A entrada da Ampersand permitir\u00e1 a expans\u00e3o da capacidade de fabrico de vectores lentivirais da empresa biotecnol\u00f3gica de Gipuzkoan e apoiar\u00e1 a execu\u00e7\u00e3o da sua carteira de projectos pioneiros de clientes que desenvolvem terapias celulares e gen\u00e9ticas inovadoras in vivo e ex vivo.            <\/div>\n            <div class=\"fecha d-flex align-items-center gap-2\">\n                <img decoding=\"async\" alt=\"icon\" src=\"https:\/\/ga-p.com\/wp-content\/themes\/ga-p\/assets\/images\/clock-icon.svg\" \/>\n                05 Dec, 2024            <\/div>\n\n\n                            <div class=\"author d-flex align-items-center gap-2\">\n                    <img decoding=\"async\" alt=\"icon\" src=\"https:\/\/ga-p.com\/wp-content\/themes\/ga-p\/assets\/images\/author-icon.svg\" \/><span>\n                    David Gonz\u00e1lez, Diana Linage, Mariana D\u00edaz-Moro, Irene Ferna\u0301ndez Puyol, Marta Rey, Lourdes Escassi, Carmen Abad, B\u00e1rbara Sa\u00ednz de Vicun\u0303a, Diego Ib\u00e1\u00f1ez, Isabel Silva, Andrew Ward, Carla Fandi\u00f1o                <\/span><\/div>\n            \n        <\/div>\n        <div class=\"openCard me-0 ms-auto\">\n            <img decoding=\"async\" alt=\"icon\" src=\"https:\/\/ga-p.com\/wp-content\/themes\/ga-p\/assets\/images\/arrow-open.svg\" \/>\n            <img decoding=\"async\" alt=\"icon\" src=\"https:\/\/ga-p.com\/wp-content\/themes\/ga-p\/assets\/images\/arrow-open.svg\" \/>\n        <\/div>\n    <\/div>\n<\/a>\n                            <\/div>\n                                                    <div class=\"swiper-slide y2024\">\n                                <a style=\"text-decoration: none\" href=\"https:\/\/ga-p.com\/pt-pt\/noticia\/a-ga_p-assessora-a-acteon-no-seu-acordo-com-a-septodont-holding-para-a-aquisicao-da-inibsa\/\">\n    <div class=\"noticiaCard\">\n        <div class=\"content\">\n            <div class=\"tag\">NOT\u00cdCIAS<\/div>\n            <div class=\"titulo\">\n                A GA_P assessora a Acteon no seu acordo com a Septodont Holding para a aquisi\u00e7\u00e3o da Inibsa            <\/div>\n            <div class=\"excerpt\">\n                A G\u00f3mez-Acebo &#038; Pombo assessorou o grupo franc\u00eas Acteon, fornecedor de solu\u00e7\u00f5es dent\u00e1rias integradas, na sua aquisi\u00e7\u00e3o, juntamente com a Septodont Holding, da Inibsa, um grupo farmac\u00eautico multinacional espanhol l\u00edder no desenvolvimento e fabrico de produtos para profissionais de medicina dent\u00e1ria.            <\/div>\n            <div class=\"fecha d-flex align-items-center gap-2\">\n                <img decoding=\"async\" alt=\"icon\" src=\"https:\/\/ga-p.com\/wp-content\/themes\/ga-p\/assets\/images\/clock-icon.svg\" \/>\n                13 Nov, 2024            <\/div>\n\n\n                            <div class=\"author d-flex align-items-center gap-2\">\n                    <img decoding=\"async\" alt=\"icon\" src=\"https:\/\/ga-p.com\/wp-content\/themes\/ga-p\/assets\/images\/author-icon.svg\" \/><span>\n                    Clara Rivero, Sergio G\u00f3mez, Oliver Padilla, Miguel Troncoso, Irene Ferna\u0301ndez Puyol, Javier Vinuesa                <\/span><\/div>\n            \n        <\/div>\n        <div class=\"openCard me-0 ms-auto\">\n            <img decoding=\"async\" alt=\"icon\" src=\"https:\/\/ga-p.com\/wp-content\/themes\/ga-p\/assets\/images\/arrow-open.svg\" \/>\n            <img decoding=\"async\" alt=\"icon\" src=\"https:\/\/ga-p.com\/wp-content\/themes\/ga-p\/assets\/images\/arrow-open.svg\" \/>\n        <\/div>\n    <\/div>\n<\/a>\n                            <\/div>\n                                                    <div class=\"swiper-slide y2024\">\n                                <a style=\"text-decoration: none\" href=\"https:\/\/ga-p.com\/pt-pt\/noticia\/ga_p-assessora-a-familia-luna-na-venda-do-grupo-ht-ao-fundo-fremman-capital\/\">\n    <div class=\"noticiaCard\">\n        <div class=\"content\">\n            <div class=\"tag\">NOT\u00cdCIAS<\/div>\n            <div class=\"titulo\">\n                GA_P assessora a Fam\u00edlia Luna na venda do Grupo HT ao fundo Fremman Capital            <\/div>\n            <div class=\"excerpt\">\n                A G\u00f3mez-Acebo &amp; Pombo assessorou a fam\u00edlia Luna na venda \u00e0 Fremman Capital de uma participa\u00e7\u00e3o maiorit\u00e1ria no Grupo HT, l\u00edder em Espanha na presta\u00e7\u00e3o de servi\u00e7os de radiologia e diagn\u00f3stico por imagem. Trata-se de uma das transac\u00e7\u00f5es mais significativas deste trimestre nos sectores de Private Equity e da Sa\u00fade. A transa\u00e7\u00e3o est\u00e1 sujeita \u00e0&#8230;            <\/div>\n            <div class=\"fecha d-flex align-items-center gap-2\">\n                <img decoding=\"async\" alt=\"icon\" src=\"https:\/\/ga-p.com\/wp-content\/themes\/ga-p\/assets\/images\/clock-icon.svg\" \/>\n                27 May, 2024            <\/div>\n\n\n                            <div class=\"author d-flex align-items-center gap-2\">\n                    <img decoding=\"async\" alt=\"icon\" src=\"https:\/\/ga-p.com\/wp-content\/themes\/ga-p\/assets\/images\/author-icon.svg\" \/><span>\n                    Pablo Fern\u00e1ndez Cortijo, Andr\u00e9s Castro, In\u00e9s L\u00f3pez Seco, Nicol\u00e1s Z\u00fa\u00f1iga, Luis Cuesta, , Irene Ferna\u0301ndez Puyol, Marta Rey, Miguel Troncoso, Eduardo G\u00f3mez de la Cruz, Jes\u00fas Antonio Urriza, Lourdes Escassi, Carmen Abad, , Isabel Band\u00edn, Natalia Lastres                <\/span><\/div>\n            \n        <\/div>\n        <div class=\"openCard me-0 ms-auto\">\n            <img decoding=\"async\" alt=\"icon\" src=\"https:\/\/ga-p.com\/wp-content\/themes\/ga-p\/assets\/images\/arrow-open.svg\" \/>\n            <img decoding=\"async\" alt=\"icon\" src=\"https:\/\/ga-p.com\/wp-content\/themes\/ga-p\/assets\/images\/arrow-open.svg\" \/>\n        <\/div>\n    <\/div>\n<\/a>\n                            <\/div>\n                                            <\/div>\n                <\/div>\n            <\/div>\n                            <div class=\"tab-pane fade \" id=\"nav-publicaciones\" role=\"tabpanel\" aria-labelledby=\"nav-publicaciones-tab\" tabindex=\"0\">\n                <div class=\"swiper mySwiper swiperPub\">\n                    <div class=\"swiper-wrapper\">\n                                                    <div class=\"swiper-slide y2018\">\n                                <div class=\"publicacionTarjeta\">\n    <div class=\"content\">\n        <a class=\"tag\" >\n            PUBLICA\u00c7\u00c3O        <\/a>\n        <div class=\"titulo\">\n            Publicidad de medicamentos, ficha t\u00e9cnica y menciones distintas de las indicaciones terap\u00e9uticas        <\/div>\n        <div class=\"excerpt\">\n            Al hilo de la Sentencia n\u00fam.\u00a0186\/2018\u00a0de la Audiencia Provincial de Barcelona\u00a0(Secci\u00f3n\u00a015.\u00aa) se examina tanto la necesidad de que la publicidad de los medicamentos se ajuste a la ficha t\u00e9cnica como la posibilidad de incluir en el mensaje publicitario menciones distintas de las indicaciones terap\u00e9uticas del medicamento.        <\/div>\n        <div class=\"fecha d-flex align-items-center gap-2\">\n            <img decoding=\"async\" alt=\"icon\" src=\"https:\/\/ga-p.com\/wp-content\/themes\/ga-p\/assets\/images\/clock-icon-fum.svg\" \/>\n            16 Jul, 2018        <\/div>\n        \n    <\/div>\n    <a href=\"https:\/\/ga-p.com\/pt-pt\/publicacoes\/publicidad-de-medicamentos-ficha-tecnica-y-menciones-distintas-de-las-indicaciones-terapeuticas-2\/\" class=\"align-self-end\">\n        <div class=\"openCard\">\n            <img decoding=\"async\" alt=\"icon\" src=\"https:\/\/ga-p.com\/wp-content\/themes\/ga-p\/assets\/images\/arrow-open-fum.svg\" \/>\n            <img decoding=\"async\" alt=\"icon\" src=\"https:\/\/ga-p.com\/wp-content\/themes\/ga-p\/assets\/images\/arrow-open-fum.svg\" \/>\n        <\/div>\n    <\/a>\n<\/div>\n                            <\/div>\n                                            <\/div>\n                <\/div>\n            <\/div>\n            <\/div>\n\n<script>\n    const opciones_noticias_publicaciones_relacionadas_array = [\n                {label: '2025', value: 'y2025'},\n                {label: '2024', value: 'y2024'},\n                {label: '2018', value: 'y2018'},\n            ]\n<\/script>\n<\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":0,"template":"","class_list":["post-66702","sector","type-sector","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Farmac\u00eautico e Sa\u00fade - Despacho de abogados G\u00f3mez-Acebo &amp; Pombo<\/title>\n<meta name=\"description\" content=\"Aconselhamento jur\u00eddico abrangente sobre produtos farmac\u00eauticos e cuidados de sa\u00fade: propriedade intelectual, regulamenta\u00e7\u00e3o, neg\u00f3cios, concorr\u00eancia e lit\u00edgios.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ga-p.com\/pt-pt\/sector\/farmaceutico-e-saude\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Farmac\u00eautico e Sa\u00fade - Despacho de abogados G\u00f3mez-Acebo &amp; Pombo\" \/>\n<meta property=\"og:description\" content=\"Aconselhamento jur\u00eddico abrangente sobre produtos farmac\u00eauticos e cuidados de sa\u00fade: propriedade intelectual, regulamenta\u00e7\u00e3o, neg\u00f3cios, concorr\u00eancia e lit\u00edgios.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ga-p.com\/pt-pt\/sector\/farmaceutico-e-saude\/\" \/>\n<meta property=\"og:site_name\" content=\"Despacho de abogados G\u00f3mez-Acebo &amp; Pombo\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-04T15:31:35+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ga-p.com\\\/pt-pt\\\/sector\\\/farmaceutico-e-saude\\\/\",\"url\":\"https:\\\/\\\/ga-p.com\\\/pt-pt\\\/sector\\\/farmaceutico-e-saude\\\/\",\"name\":\"Farmac\u00eautico e Sa\u00fade - Despacho de abogados G\u00f3mez-Acebo &amp; Pombo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ga-p.com\\\/pt-pt\\\/#website\"},\"datePublished\":\"2024-04-17T07:55:50+00:00\",\"dateModified\":\"2025-06-04T15:31:35+00:00\",\"description\":\"Aconselhamento jur\u00eddico abrangente sobre produtos farmac\u00eauticos e cuidados de sa\u00fade: propriedade intelectual, regulamenta\u00e7\u00e3o, neg\u00f3cios, concorr\u00eancia e lit\u00edgios.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ga-p.com\\\/pt-pt\\\/sector\\\/farmaceutico-e-saude\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ga-p.com\\\/pt-pt\\\/sector\\\/farmaceutico-e-saude\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ga-p.com\\\/pt-pt\\\/sector\\\/farmaceutico-e-saude\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/ga-p.com\\\/pt-pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Farmac\u00eautico e Sa\u00fade\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ga-p.com\\\/pt-pt\\\/#website\",\"url\":\"https:\\\/\\\/ga-p.com\\\/pt-pt\\\/\",\"name\":\"Despacho de abogados G\u00f3mez-Acebo & Pombo\",\"description\":\"G\u00f3mez-Acebo &amp; Pombo es una firma de abogados independiente, con experiencia internacional, especializada en todas las \u00e1reas del derecho de los negocio.\",\"publisher\":{\"@id\":\"https:\\\/\\\/ga-p.com\\\/pt-pt\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ga-p.com\\\/pt-pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ga-p.com\\\/pt-pt\\\/#organization\",\"name\":\"Despacho de abogados G\u00f3mez-Acebo & Pombo\",\"url\":\"https:\\\/\\\/ga-p.com\\\/pt-pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/ga-p.com\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/ga-p.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Logo-1-1.svg\",\"contentUrl\":\"https:\\\/\\\/ga-p.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Logo-1-1.svg\",\"caption\":\"Despacho de abogados G\u00f3mez-Acebo & Pombo\"},\"image\":{\"@id\":\"https:\\\/\\\/ga-p.com\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Farmac\u00eautico e Sa\u00fade - Despacho de abogados G\u00f3mez-Acebo &amp; Pombo","description":"Aconselhamento jur\u00eddico abrangente sobre produtos farmac\u00eauticos e cuidados de sa\u00fade: propriedade intelectual, regulamenta\u00e7\u00e3o, neg\u00f3cios, concorr\u00eancia e lit\u00edgios.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ga-p.com\/pt-pt\/sector\/farmaceutico-e-saude\/","og_locale":"pt_PT","og_type":"article","og_title":"Farmac\u00eautico e Sa\u00fade - Despacho de abogados G\u00f3mez-Acebo &amp; Pombo","og_description":"Aconselhamento jur\u00eddico abrangente sobre produtos farmac\u00eauticos e cuidados de sa\u00fade: propriedade intelectual, regulamenta\u00e7\u00e3o, neg\u00f3cios, concorr\u00eancia e lit\u00edgios.","og_url":"https:\/\/ga-p.com\/pt-pt\/sector\/farmaceutico-e-saude\/","og_site_name":"Despacho de abogados G\u00f3mez-Acebo &amp; Pombo","article_modified_time":"2025-06-04T15:31:35+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ga-p.com\/pt-pt\/sector\/farmaceutico-e-saude\/","url":"https:\/\/ga-p.com\/pt-pt\/sector\/farmaceutico-e-saude\/","name":"Farmac\u00eautico e Sa\u00fade - Despacho de abogados G\u00f3mez-Acebo &amp; Pombo","isPartOf":{"@id":"https:\/\/ga-p.com\/pt-pt\/#website"},"datePublished":"2024-04-17T07:55:50+00:00","dateModified":"2025-06-04T15:31:35+00:00","description":"Aconselhamento jur\u00eddico abrangente sobre produtos farmac\u00eauticos e cuidados de sa\u00fade: propriedade intelectual, regulamenta\u00e7\u00e3o, neg\u00f3cios, concorr\u00eancia e lit\u00edgios.","breadcrumb":{"@id":"https:\/\/ga-p.com\/pt-pt\/sector\/farmaceutico-e-saude\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ga-p.com\/pt-pt\/sector\/farmaceutico-e-saude\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ga-p.com\/pt-pt\/sector\/farmaceutico-e-saude\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/ga-p.com\/pt-pt\/"},{"@type":"ListItem","position":2,"name":"Farmac\u00eautico e Sa\u00fade"}]},{"@type":"WebSite","@id":"https:\/\/ga-p.com\/pt-pt\/#website","url":"https:\/\/ga-p.com\/pt-pt\/","name":"Despacho de abogados G\u00f3mez-Acebo & Pombo","description":"G\u00f3mez-Acebo &amp; Pombo es una firma de abogados independiente, con experiencia internacional, especializada en todas las \u00e1reas del derecho de los negocio.","publisher":{"@id":"https:\/\/ga-p.com\/pt-pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ga-p.com\/pt-pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/ga-p.com\/pt-pt\/#organization","name":"Despacho de abogados G\u00f3mez-Acebo & Pombo","url":"https:\/\/ga-p.com\/pt-pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/ga-p.com\/pt-pt\/#\/schema\/logo\/image\/","url":"https:\/\/ga-p.com\/wp-content\/uploads\/2024\/09\/Logo-1-1.svg","contentUrl":"https:\/\/ga-p.com\/wp-content\/uploads\/2024\/09\/Logo-1-1.svg","caption":"Despacho de abogados G\u00f3mez-Acebo & Pombo"},"image":{"@id":"https:\/\/ga-p.com\/pt-pt\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/ga-p.com\/pt-pt\/wp-json\/wp\/v2\/sector\/66702","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ga-p.com\/pt-pt\/wp-json\/wp\/v2\/sector"}],"about":[{"href":"https:\/\/ga-p.com\/pt-pt\/wp-json\/wp\/v2\/types\/sector"}],"wp:attachment":[{"href":"https:\/\/ga-p.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=66702"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}